
{"id":71802,"date":"2014-11-25T07:24:34","date_gmt":"2014-11-25T10:24:34","guid":{"rendered":"http:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=71802"},"modified":"2014-11-24T22:26:39","modified_gmt":"2014-11-25T01:26:39","slug":"itabuna-prefeitura-troca-nomes-de-avenidas","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2014\/11\/25\/itabuna-prefeitura-troca-nomes-de-avenidas\/","title":{"rendered":"ITABUNA: PREFEITURA TROCA NOMES DE AVENIDAS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-71803\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2014\/11\/1656283_568503383245767_952328683_n.jpg\" alt=\"1656283_568503383245767_952328683_n\" width=\"430\" height=\"323\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2014\/11\/1656283_568503383245767_952328683_n.jpg 960w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2014\/11\/1656283_568503383245767_952328683_n-300x225.jpg 300w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/p>\n<h4 style=\"text-align: justify;\">Em Itabuna parece que a prefeitura mudou o nome de uma avenida sem consultar a c\u00e2mara de vereadores. J\u00e1 que colocou uma placa com o nome da avenida Jos\u00e9 Soares Pinheiro no local onde fica a avenida Na\u00e7\u00f5es Unidas.<\/h4>\n<h4 style=\"text-align: justify;\">Vale lembrar que a avenida Jos\u00e9 Soares Pinheiro fica na antiga avenida Ibicara\u00ed, avenida onde fica o col\u00e9gio modelo.<\/h4>\n<h4 style=\"text-align: justify;\">Vale lembrar que tem muito tempo que a placa foi colocada no local errado, mas nenhum membro do governo teve a inciativa de corrigir o erro.<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Em Itabuna parece que a prefeitura mudou o nome de uma avenida sem consultar a c\u00e2mara de vereadores. J\u00e1 que colocou uma placa com o nome da avenida Jos\u00e9 Soares Pinheiro no local onde fica a avenida Na\u00e7\u00f5es Unidas. Vale lembrar que a avenida Jos\u00e9 Soares Pinheiro fica na antiga avenida Ibicara\u00ed, avenida onde fica [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-71802","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":942,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/71802"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=71802"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/71802\/revisions"}],"predecessor-version":[{"id":71804,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/71802\/revisions\/71804"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=71802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=71802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=71802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}