
{"id":59521,"date":"2013-08-27T11:58:48","date_gmt":"2013-08-27T14:58:48","guid":{"rendered":"http:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=59521"},"modified":"2013-08-27T11:58:49","modified_gmt":"2013-08-27T14:58:49","slug":"buerarema-geraldo-simoes-defende-a-suspensao-do-processo-de-demarcacao-realizado-pela-funai","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2013\/08\/27\/buerarema-geraldo-simoes-defende-a-suspensao-do-processo-de-demarcacao-realizado-pela-funai\/","title":{"rendered":"BUERAREMA: GERALDO SIM\u00d5ES DEFENDE A SUSPENS\u00c3O DO PROCESSO DE  DEMARCA\u00c7\u00c3O REALIZADO PELA FUNAI"},"content":{"rendered":"<p><a href=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/2013\/08\/27\/buerarema-geraldo-simoes-defende-a-suspensao-do-processo-de-demarcacao-realizado-pela-funai\/gs-8\/\" rel=\"attachment wp-att-59522\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-59522\" alt=\"gs\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2013\/08\/gs.jpg\" width=\"194\" height=\"259\" \/><\/a><\/p>\n<h4 style=\"text-align: justify;\">O deputado federal Geraldo Sim\u00f5es (PT), solicitou nesta ter\u00e7a-feira ao \u00a0coordenador da bancada da Bahia, deputado Daniel Almeida (PCdoB), uma reuni\u00e3o com toda a bancada para defender o pleito de suspender o estudo de demarca\u00e7\u00e3o das terras reivindicadas pelos \u00edndios, cujo o estudo foi realizado pela FUNAI, e nos estudos realizados por este \u00f3rg\u00e3o sempre \u00e9 a favor dos \u00edndios.<\/h4>\n<h4 style=\"text-align: justify;\">\u201c prova disso \u00e9 que o governo mudou, agora quem faz os estudos n\u00e3o \u00e9 apenas a FUNAI, mas sim Embrapa, Minist\u00e9rio do Desenvolvimento Agr\u00e1rio e o Minist\u00e9rio das Cidades. O processo de demarca\u00e7\u00e3o de terras efetuado pela FUNAI deve ser suspenso e reavaliado\u201d.<\/h4>\n<h4 style=\"text-align: justify;\">A disputa de terra entre produtores em \u00edndios ocorre h\u00e1 cerca de uma semana em Buerarema.<\/h4>\n<h4 style=\"text-align: justify;\">Geraldo Sim\u00f5es defende que o Ministro da Justi\u00e7a, Jos\u00e9 Eduardo Cardoso, suspende esse estudo, e mande fazer um novo estudo com a equipe t\u00e9cnica formada por esse corpo de t\u00e9cnicos destes \u00f3rg\u00e3os.<\/h4>\n<h4 style=\"text-align: justify;\">\u201c Se ficar comprovada neste novo estudo \u00e1rea de terra ind\u00edgena na regi\u00e3o,o governo federal compra uma \u00e1rea, n\u00e3o de 47 mil hectares, para deixar a disposi\u00e7\u00e3o dos \u00edndios. Os verdadeiros ind\u00edgenas que assim forem reconhecidos dever\u00e3o ter acesso a suas terras por meio de um processo pac\u00edfico e legal.\u201d, declarou Geraldo.<\/h4>\n<h4 style=\"text-align: justify;\">Nesta quarta-feira a comiss\u00e3o de agricultura da c\u00e2mara dos deputados vai votar um requerimento convocando o Ministro da Justi\u00e7a, Jos\u00e9 Eduardo Cardoso, o governador Wagner (PT), e os produtores para uma audi\u00eancia sobre o tema.<\/h4>\n<h4 style=\"text-align: justify;\">\u201c n\u00e3o tem que acelerar o processo de demarca\u00e7\u00e3o das terras reivindicadas pelos \u00edndios para garantir uma indeniza\u00e7\u00e3o justa aos agricultores que perder\u00e3o suas propriedades, j\u00e1 que neste caso a indeniza\u00e7\u00e3o \u00e9 apenas da benfeitoria da propriedade, e nessa regi\u00e3o s\u00e3o pequenos produtores. Tem que realizar um estudo de demarca\u00e7\u00e3o mais justo e imparcial\u201d, finalizou Geraldo.<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>O deputado federal Geraldo Sim\u00f5es (PT), solicitou nesta ter\u00e7a-feira ao \u00a0coordenador da bancada da Bahia, deputado Daniel Almeida (PCdoB), uma reuni\u00e3o com toda a bancada para defender o pleito de suspender o estudo de demarca\u00e7\u00e3o das terras reivindicadas pelos \u00edndios, cujo o estudo foi realizado pela FUNAI, e nos estudos realizados por este \u00f3rg\u00e3o sempre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-59521","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":2234,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/59521"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=59521"}],"version-history":[{"count":4,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/59521\/revisions"}],"predecessor-version":[{"id":59526,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/59521\/revisions\/59526"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=59521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=59521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=59521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}