
{"id":198869,"date":"2026-07-14T17:13:05","date_gmt":"2026-07-14T20:13:05","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=198869"},"modified":"2026-07-14T17:13:05","modified_gmt":"2026-07-14T20:13:05","slug":"brumado-prefeito-fabricio-abrantes-e-alvo-de-fake-news-apos-discurso-manipulado","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2026\/07\/14\/brumado-prefeito-fabricio-abrantes-e-alvo-de-fake-news-apos-discurso-manipulado\/","title":{"rendered":"BRUMADO: PREFEITO FABR\u00cdCIO ABRANTES \u00c9 ALVO DE FAKE NEWS AP\u00d3S DISCURSO MANIPULADO"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-198870\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/07\/fabricio-br.jpg\" alt=\"\" width=\"450\" height=\"450\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/07\/fabricio-br.jpg 450w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/07\/fabricio-br-300x300.jpg 300w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/07\/fabricio-br-150x150.jpg 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">O prefeito de Brumado, Fabr\u00edcio Abrantes (Avante), foi alvo de uma fake news ap\u00f3s advers\u00e1rios divulgarem um trecho editado de seu discurso durante a inaugura\u00e7\u00e3o do novo sistema de abastecimento de \u00e1gua que atender\u00e1 as comunidades de Ubira\u00e7aba, Samambaia, Lagoa de S\u00e3o Jo\u00e3o, Lagoa de Isidoro, Lagoinha, Tamboril e Marquinhos.<\/h3>\n<h3 style=\"text-align: justify;\">A edi\u00e7\u00e3o tentou criar a vers\u00e3o de que Fabr\u00edcio teria criticado o governador Jer\u00f4nimo Rodrigues. O prefeito, por\u00e9m, afirmou ao site que se referia ao grupo pol\u00edtico que faz oposi\u00e7\u00e3o ao seu governo.<\/h3>\n<h3 style=\"text-align: justify;\">\n\u201cEu disse que o grupo do PT est\u00e1 no poder h\u00e1 20 anos no estado e o grupo de oposi\u00e7\u00e3o ao nosso governo n\u00e3o conseguiu realizar essas obras em Brumado. Em pouco menos de dois anos, nosso governo transformou a cidade em um canteiro de obras. Cortaram parte da fala para insinuar que eu critiquei o governador. Isso \u00e9 uma fake news\u201d, declarou.<\/h3>\n<h3 style=\"text-align: justify;\">A apura\u00e7\u00e3o do site aponta que a montagem circulou a partir de integrantes do grupo petista derrotado por Fabr\u00edcio nas elei\u00e7\u00f5es de 2024.<\/p>\n<p>Nos bastidores, a avalia\u00e7\u00e3o \u00e9 que a tentativa de desgastar o prefeito teve efeito contr\u00e1rio. Ao tentar criar uma crise entre Fabr\u00edcio e o governo estadual, a oposi\u00e7\u00e3o acabou produzindo conte\u00fado que tamb\u00e9m favorece politicamente o grupo de ACM Neto.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Brumado, Fabr\u00edcio Abrantes (Avante), foi alvo de uma fake news ap\u00f3s advers\u00e1rios divulgarem um trecho editado de seu discurso durante a inaugura\u00e7\u00e3o do novo sistema de abastecimento de \u00e1gua que atender\u00e1 as comunidades de Ubira\u00e7aba, Samambaia, Lagoa de S\u00e3o Jo\u00e3o, Lagoa de Isidoro, Lagoinha, Tamboril e Marquinhos. A edi\u00e7\u00e3o tentou criar a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":198870,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-198869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":150,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/198869"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=198869"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/198869\/revisions"}],"predecessor-version":[{"id":198871,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/198869\/revisions\/198871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/198870"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=198869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=198869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=198869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}