
{"id":197883,"date":"2026-05-11T16:52:56","date_gmt":"2026-05-11T19:52:56","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=197883"},"modified":"2026-05-11T16:52:56","modified_gmt":"2026-05-11T19:52:56","slug":"novo-sistema-viario-da-ba-649-entre-ilheus-e-itabuna-tem-o-investimento-de-r-290-milhoes","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2026\/05\/11\/novo-sistema-viario-da-ba-649-entre-ilheus-e-itabuna-tem-o-investimento-de-r-290-milhoes\/","title":{"rendered":"NOVO SISTEMA VI\u00c1RIO DA BA-649, ENTRE ILH\u00c9US E ITABUNA, TEM O INVESTIMENTO DE R$ 290 MILH\u00d5ES"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-197884\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-11-at-16.39.13.jpeg\" alt=\"\" width=\"455\" height=\"341\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-11-at-16.39.13.jpeg 600w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-11-at-16.39.13-300x225.jpeg 300w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-11-at-16.39.13-400x300.jpeg 400w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/p>\n<h4 style=\"text-align: center\"><strong><em>Obras t\u00eam a previs\u00e3o serem conclu\u00eddas ainda neste primeiro semestre deste ano<\/em><\/strong><\/h4>\n<h3 style=\"text-align: justify\">Assim que estiver totalmente pronto, ainda no primeiro semestre deste ano, o Sistema Vi\u00e1rio da BA-649, entre Ilh\u00e9us e Itabuna, se tornar\u00e1 um importante vetor para o desenvolvimento do turismo, principalmente para quem vai visitar as praias, e da agricultura, como a produ\u00e7\u00e3o do Cacau, na regi\u00e3o do Litoral Sul baiano. Um total de 8 obras quem vem sendo realizadas pelo Governo da Bahia, atrav\u00e9s da Secretaria de Infraestrutura do Estado (Seinfra), com um investimento de mais de R$ 290 milh\u00f5es. S\u00e3o a\u00e7\u00f5es que contribuir\u00e3o na melhoria do tr\u00e1fego entre os munic\u00edpios, al\u00e9m da atra\u00e7\u00e3o de novos neg\u00f3cios no entorno.<\/h3>\n<h3 style=\"text-align: justify\">Sobre a 1\u00aa etapa das a\u00e7\u00f5es, a implanta\u00e7\u00e3o dos 18 km da BA-649, incluindo duas faixas, ciclovia e acostamento, j\u00e1 est\u00e1 com 92% de execu\u00e7\u00e3o. A constru\u00e7\u00e3o das pontes 01 e 04 e do viaduto se encontram 98%, 99% e 95% conclu\u00eddas, respectivamente. Para finalizar os trabalhos no viaduto, a Seinfra aguarda imiss\u00e3o na posse de \u00e1rea para executar o aterro de um dos encontros. Em rela\u00e7\u00e3o as pontes 02 e 03, que correspondem a 2\u00aa etapa da obra, ambas est\u00e3o 70% executadas. Tamb\u00e9m fazendo parte do Sistema Vi\u00e1rio, a duplica\u00e7\u00e3o de 2,3 km do acesso a Itabuna, na BA-963, que fica na margem esquerda do Rio Cachoeira, est\u00e1 91% pronta. A implanta\u00e7\u00e3o do trecho de 5,1 km do entroncamento da BA-693 at\u00e9 o acesso a Itabuna, na margem direita do Rio Cachoeira, se encontra 95% executada.<\/h3>\n<h3 style=\"text-align: justify\">A rodovia em constru\u00e7\u00e3o formar\u00e1 um bin\u00e1rio com a BR-415, cuja conex\u00e3o ser\u00e1 feita atrav\u00e9s das quatro pontes e do viaduto que est\u00e3o sendo implantados. A obra est\u00e1 sendo feita com pistas duplas em cada sentido, reduzindo o risco de colis\u00f5es frontais e garantindo mais seguran\u00e7a para quem utiliza a rodovia. Ou seja, o tr\u00e2nsito na BA-649 ser\u00e1 de Itabuna sentido Ilh\u00e9us e na BR-415 ser\u00e1 no sentido oposto e as pontes funcionar\u00e3o como retorno entre as duas rodovias.<\/h3>\n<h3 style=\"text-align: justify\">O maior bi-polo populacional do interior do estado tamb\u00e9m recebe outras a\u00e7\u00f5es de mobilidade urbana, de acordo com Saulo Pontes, secret\u00e1rio de Infraestrutura. \u201cAl\u00e9m do Sistema Vi\u00e1rio da BA-649, estamos realizando outras importantes obras de Infraestrutura na regi\u00e3o. A pavimenta\u00e7\u00e3o e a requalifica\u00e7\u00e3o dos 2,8 km da Zona Norte de Ilh\u00e9us, na BA-262, est\u00e1 60% executada e deve ser conclu\u00edda no m\u00eas de junho. J\u00e1 estamos programando a assinatura da ordem de servi\u00e7o para a execu\u00e7\u00e3o dos servi\u00e7os remanescentes da pavimenta\u00e7\u00e3o e de requalifica\u00e7\u00e3o dos 3,5 km da Zona Sul de Ilh\u00e9us, na BA-001,\u201d destaca o secret\u00e1rio acrescentando tamb\u00e9m que os servi\u00e7os de manuten\u00e7\u00e3o na BA-001, saindo de Ilh\u00e9us em dire\u00e7\u00e3o ao KM 18, em Canavieiras, passando por Oliven\u00e7a e Una, foram retomados na \u00faltima ter\u00e7a-feira (05).<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Obras t\u00eam a previs\u00e3o serem conclu\u00eddas ainda neste primeiro semestre deste ano Assim que estiver totalmente pronto, ainda no primeiro semestre deste ano, o Sistema Vi\u00e1rio da BA-649, entre Ilh\u00e9us e Itabuna, se tornar\u00e1 um importante vetor para o desenvolvimento do turismo, principalmente para quem vai visitar as praias, e da agricultura, como a produ\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":992,"featured_media":197884,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"class_list":["post-197883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades"],"views":89,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/197883"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/992"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=197883"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/197883\/revisions"}],"predecessor-version":[{"id":197885,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/197883\/revisions\/197885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/197884"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=197883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=197883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=197883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}