
{"id":196216,"date":"2026-02-06T14:24:44","date_gmt":"2026-02-06T17:24:44","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=196216"},"modified":"2026-02-06T14:24:44","modified_gmt":"2026-02-06T17:24:44","slug":"itabuna-prefeitura-realiza-na-sexta-e-no-sabado-o-1o-mutirao-mais-saude-menos-fila","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2026\/02\/06\/itabuna-prefeitura-realiza-na-sexta-e-no-sabado-o-1o-mutirao-mais-saude-menos-fila\/","title":{"rendered":"ITABUNA: PREFEITURA REALIZA NA SEXTA E NO S\u00c1BADO O 1\u00ba MUTIR\u00c3O MAIS SA\u00daDE, MENOS FILA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-196217\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/02\/Praca-Rio-Cachoeira-recebera-o-Mutirao-Mais-Saude-Menos-Filas-nos-dias-6-e-7-Fotos-Roberto-Santos-5.jpg\" alt=\"\" width=\"450\" height=\"253\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/02\/Praca-Rio-Cachoeira-recebera-o-Mutirao-Mais-Saude-Menos-Filas-nos-dias-6-e-7-Fotos-Roberto-Santos-5.jpg 450w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/02\/Praca-Rio-Cachoeira-recebera-o-Mutirao-Mais-Saude-Menos-Filas-nos-dias-6-e-7-Fotos-Roberto-Santos-5-300x169.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">A Prefeitura de Itabuna, por meio da Secretaria Municipal de Sa\u00fade, realiza nesta sexta-feira, dia 6, e no s\u00e1bado, dia 7, das 8 \u00e0s 17 horas, na Pra\u00e7a Rio Cachoeira, o 1\u00ba \u201cMutir\u00e3o Mais Sa\u00fade, Menos Filas\u201d.<\/h3>\n<h3 style=\"text-align: justify;\">Trata-se de uma a\u00e7\u00e3o coordenada pelo Instituto SETES, uma organiza\u00e7\u00e3o privada sem fins lucrativos com experi\u00eancia em gest\u00e3o, desde 2009, O objetivo do Mutir\u00e3o \u00e9 fortalecer a Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade.<\/h3>\n<h3 style=\"text-align: justify;\">O Mutir\u00e3o contar\u00e1 com atendimento de m\u00e9dicos especialistas em Neurologia e Cardiologista, al\u00e9m de exames de ECO e Pr\u00e1ticas Integrativas. A expectativa \u00e9 de que cerca de 800 pacientes sejam atendidos nos dois dias. O encaminhamento dos pacientes para o Mutir\u00e3o est\u00e1 sendo feito, exclusivamente, pelas Unidades de Sa\u00fade.<\/p>\n<p>Vale ressaltar que o Mutir\u00e3o Mais Sa\u00fade, Menos Filas \u00e9 uma continuidade do Projeto \u201cMais Sa\u00fade, Menos Fila \u2013 Fortalecendo a APS\u201d que j\u00e1 vem sendo executado com a proposta de fortalecer a Aten\u00e7\u00e3o Prim\u00e1ria, que \u00e9 a porta de entrada para os servi\u00e7os de sa\u00fade, tendo como consequ\u00eancia o cuidado integral do indiv\u00edduo e a redu\u00e7\u00e3o da demanda reprimida por servi\u00e7os especializados.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Itabuna, por meio da Secretaria Municipal de Sa\u00fade, realiza nesta sexta-feira, dia 6, e no s\u00e1bado, dia 7, das 8 \u00e0s 17 horas, na Pra\u00e7a Rio Cachoeira, o 1\u00ba \u201cMutir\u00e3o Mais Sa\u00fade, Menos Filas\u201d. Trata-se de uma a\u00e7\u00e3o coordenada pelo Instituto SETES, uma organiza\u00e7\u00e3o privada sem fins lucrativos com experi\u00eancia em gest\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":196217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-196216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":112,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/196216"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=196216"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/196216\/revisions"}],"predecessor-version":[{"id":196218,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/196216\/revisions\/196218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/196217"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=196216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=196216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=196216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}