
{"id":196209,"date":"2026-02-05T20:27:28","date_gmt":"2026-02-05T23:27:28","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=196209"},"modified":"2026-02-05T20:27:28","modified_gmt":"2026-02-05T23:27:28","slug":"policia-militar-da-bahia-tem-a-primeira-mulher-promovida-ao-posto-de-coronel-na-historia","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2026\/02\/05\/policia-militar-da-bahia-tem-a-primeira-mulher-promovida-ao-posto-de-coronel-na-historia\/","title":{"rendered":"POL\u00cdCIA MILITAR DA BAHIA TEM A PRIMEIRA MULHER PROMOVIDA AO POSTO DE CORONEL NA HIST\u00d3RIA"},"content":{"rendered":"<h3 style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-196210 aligncenter\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-14.39.17.jpeg\" alt=\"\" width=\"455\" height=\"303\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-14.39.17.jpeg 1600w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-14.39.17-300x200.jpeg 300w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-14.39.17-1024x682.jpeg 1024w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-14.39.17-768x512.jpeg 768w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-05-at-14.39.17-1536x1023.jpeg 1536w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/h3>\n<h3 style=\"text-align: justify\">A promo\u00e7\u00e3o da tenente-coronel PM Ivana Teixeira Andrade, que integra o Quadro de Oficiais de Sa\u00fade (QOS), a coronel \u2013 o mais alto posto da Pol\u00edcia Militar da Bahia (PMBA), representa um marco hist\u00f3rico na bicenten\u00e1ria corpora\u00e7\u00e3o. O ato simboliza um avan\u00e7o significativo para a representatividade feminina nas for\u00e7as de seguran\u00e7a do estado. Graduada em Odontologia pela Universidade Federal da Bahia (UFBA) e formada no Curso de Comando e Estado Maior (CCEM), pr\u00e9-requisito para assumir o posto, a coronel Ivana tem uma trajet\u00f3ria de 32 anos na corpora\u00e7\u00e3o, que une a precis\u00e3o da sa\u00fade com a exatid\u00e3o da estrat\u00e9gia militar.<\/h3>\n<h3 style=\"text-align: justify\">Ao longo da carreira, a oficiala, que tem 56 anos, foi reconhecida com a Medalha Marechal Argolo, a Medalha Tr\u00eas Marias e as medalhas de 10, 20 e 30 anos de servi\u00e7os prestados \u00e0 corpora\u00e7\u00e3o. Ela conta ter prestado o concurso da PM para o Quadro de Sa\u00fade aos 24 anos, rec\u00e9m-formada, quando ainda n\u00e3o fazia ideia do que era ser policial militar. Mas, como sempre foi disciplinada, adaptou-se r\u00e1pido e construiu uma carreira longa e s\u00f3lida, primeiramente atendendo e depois assumindo a gest\u00e3o da Odontocl\u00ednica.<\/h3>\n<h3 style=\"text-align: justify\">\u201cEu me sinto honrada de estar aqui neste lugar, ocupando esse espa\u00e7o, e espero em breve que muitas mulheres estejam aqui\u201d, disse emocionada a coronel e dentista. As novas promo\u00e7\u00f5es, anunciadas pelo governador Jer\u00f4nimo Rodrigues e publicadas no Di\u00e1rio Oficial do Estado (DOE) do dia 4 de fevereiro, fazem parte de um total de 130 que recomp\u00f5e o quadro de oficiais e cumpre um compromisso da gest\u00e3o estadual pelo fortalecimento da tropa. O segundo maior posto, o de tenente coronel, tamb\u00e9m ganhou destaque sendo alcan\u00e7ado, nesta promo\u00e7\u00e3o, por 11 oficialas.<\/h3>\n<h3 style=\"text-align: justify\">\u00a0\u201cN\u00f3s mulheres temos uma vida muito cheia de atividades, porque n\u00f3s somos esposas, m\u00e3es, filhas, e quando a gente volta para casa, tem que lidar com toda essa situa\u00e7\u00e3o. A\u00ed que est\u00e1 a grande dificuldade da mulher e tamb\u00e9m a for\u00e7a\u201d, completou a coronel Ivana Andrade.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A promo\u00e7\u00e3o da tenente-coronel PM Ivana Teixeira Andrade, que integra o Quadro de Oficiais de Sa\u00fade (QOS), a coronel \u2013 o mais alto posto da Pol\u00edcia Militar da Bahia (PMBA), representa um marco hist\u00f3rico na bicenten\u00e1ria corpora\u00e7\u00e3o. O ato simboliza um avan\u00e7o significativo para a representatividade feminina nas for\u00e7as de seguran\u00e7a do estado. Graduada em [&hellip;]<\/p>\n","protected":false},"author":992,"featured_media":196210,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"class_list":["post-196209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades"],"views":186,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/196209"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/992"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=196209"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/196209\/revisions"}],"predecessor-version":[{"id":196211,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/196209\/revisions\/196211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/196210"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=196209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=196209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=196209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}