
{"id":195013,"date":"2025-12-03T15:18:00","date_gmt":"2025-12-03T18:18:00","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=195013"},"modified":"2025-12-03T15:18:00","modified_gmt":"2025-12-03T18:18:00","slug":"arataca-prefeitura-articula-novo-posto-de-atendimento-do-sicoob-coopec","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/12\/03\/arataca-prefeitura-articula-novo-posto-de-atendimento-do-sicoob-coopec\/","title":{"rendered":"ARATACA: PREFEITURA ARTICULA NOVO POSTO DE ATENDIMENTO DO SICOOB COOPEC"},"content":{"rendered":"<h3 style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-195014 aligncenter\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-03-at-13.48.43.jpeg\" alt=\"\" width=\"455\" height=\"343\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-03-at-13.48.43.jpeg 1280w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-03-at-13.48.43-300x226.jpeg 300w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-03-at-13.48.43-1024x772.jpeg 1024w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-03-at-13.48.43-768x579.jpeg 768w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/h3>\n<h3 style=\"text-align: justify\">O prefeito de Arataca, Ferl\u00fa Mansur, e o secret\u00e1rio de Administra\u00e7\u00e3o, Vitor Mansur, se reuniram nesta quarta-feira com representantes do SICOOB COOPEC para discutir a instala\u00e7\u00e3o de um novo posto de atendimento banc\u00e1rio no munic\u00edpio. O encontro aconteceu na sede da Prefeitura.<\/h3>\n<h3 style=\"text-align: justify\">Participaram da reuni\u00e3o Thais Muniz, diretora de Neg\u00f3cios, Valdemir Souza, diretor Administrativo, e Ant\u00f4nio Vidal, presidente da ag\u00eancia do SICOOB COOPEC em Arataca.<\/h3>\n<h3 style=\"text-align: justify\">A proposta tem como objetivo ampliar o acesso da popula\u00e7\u00e3o a servi\u00e7os banc\u00e1rios como saques, dep\u00f3sitos, pagamentos e consultas, evitando o deslocamento para cidades vizinhas.<\/h3>\n<h3 style=\"text-align: justify\">Segundo o prefeito Ferl\u00fa Mansur, a iniciativa busca facilitar a vida dos moradores, especialmente dos que vivem em \u00e1reas mais afastadas. J\u00e1 o secret\u00e1rio Vitor Mansur destacou que o novo posto pode impulsionar o com\u00e9rcio local e fortalecer a economia do munic\u00edpio.<\/h3>\n<h3 style=\"text-align: justify\">Os representantes do SICOOB COOPEC informaram que ir\u00e3o avaliar a viabilidade t\u00e9cnica e financeira do projeto. A expectativa da gest\u00e3o municipal \u00e9 que, em breve, a popula\u00e7\u00e3o possa contar com o novo servi\u00e7o.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Arataca, Ferl\u00fa Mansur, e o secret\u00e1rio de Administra\u00e7\u00e3o, Vitor Mansur, se reuniram nesta quarta-feira com representantes do SICOOB COOPEC para discutir a instala\u00e7\u00e3o de um novo posto de atendimento banc\u00e1rio no munic\u00edpio. O encontro aconteceu na sede da Prefeitura. Participaram da reuni\u00e3o Thais Muniz, diretora de Neg\u00f3cios, Valdemir Souza, diretor Administrativo, e [&hellip;]<\/p>\n","protected":false},"author":992,"featured_media":195014,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"class_list":["post-195013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades"],"views":220,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/195013"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/992"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=195013"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/195013\/revisions"}],"predecessor-version":[{"id":195015,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/195013\/revisions\/195015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/195014"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=195013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=195013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=195013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}