
{"id":194597,"date":"2025-11-13T09:52:01","date_gmt":"2025-11-13T12:52:01","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=194597"},"modified":"2025-11-13T09:52:01","modified_gmt":"2025-11-13T12:52:01","slug":"itabuna-mutirao-do-diabetes-tera-atendimento-especializado-no-hbr-e-acoes-de-prevencao","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/11\/13\/itabuna-mutirao-do-diabetes-tera-atendimento-especializado-no-hbr-e-acoes-de-prevencao\/","title":{"rendered":"ITABUNA: MUTIR\u00c3O DO DIABETES TER\u00c1 ATENDIMENTO ESPECIALIZADO NO HBR E A\u00c7\u00d5ES DE PREVEN\u00c7\u00c3O"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-194598 aligncenter\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-13-at-09.48.09.jpeg\" alt=\"\" width=\"455\" height=\"258\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-13-at-09.48.09.jpeg 1024w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-13-at-09.48.09-300x170.jpeg 300w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-13-at-09.48.09-768x435.jpeg 768w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/p>\n<h3 style=\"text-align: justify\">Ser\u00e1 realizada neste s\u00e1bado, a 21\u00aa. edi\u00e7\u00e3o do Mutir\u00e3o do Diabetes de Itabuna, considerado um dos mais impactantes eventos de preven\u00e7\u00e3o e tratamento da doen\u00e7a da Am\u00e9rica Latina e que integra o calend\u00e1rio da Federa\u00e7\u00e3o Internacional do Diabetes. O mutir\u00e3o ter\u00e1 atendimento especializado no Hospital Beira Rio e a\u00e7\u00f5es de preven\u00e7\u00e3o na Cidade do Diabetes-Pra\u00e7a Rio Cachoeira.<\/h3>\n<h3 style=\"text-align: justify\">No HBR, cerca de mil pacientes com Diabetes, em uma parceria com a Secretaria Municipal de Sa\u00fade, realizar\u00e3o exames de retinografia digital com Intelig\u00eancia Artificial, e fundo de olho com mapeamento de retina, e se graves, realizar\u00e3o tomografia da retina, fotocoagula\u00e7\u00e3o a laser, e, pacientes com maior risco devido a retinopatia diab\u00e9tica grave, far\u00e3o avalia\u00e7\u00f5es laboratorial, renal, cardiol\u00f3gica, e em alguns casos com p\u00e9 diab\u00e9tico de alto risco, avalia\u00e7\u00e3o angiol\u00f3gica e curativos especializados.<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-194599 aligncenter\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-13-at-09.48.10.jpeg\" alt=\"\" width=\"455\" height=\"303\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-13-at-09.48.10.jpeg 455w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-13-at-09.48.10-300x200.jpeg 300w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/p>\n<h3 style=\"text-align: justify\">Na Cidade do Diabetes, ser\u00e3o oferecidos para toda a comunidade servi\u00e7os como detec\u00e7\u00e3o de novos casos de diabetes com cerca de 2000 exames de glicemia capilar, avalia\u00e7\u00e3o endocrinol\u00f3gica e de risco de diabetes, orienta\u00e7\u00e3o e oficina nutricional, educa\u00e7\u00e3o e diabetes, educa\u00e7\u00e3o em diabetes, conhecendo a insulina, oficina do p\u00e9 diab\u00e9tico, sa\u00fade bucal e avalia\u00e7\u00e3o auditiva e sa\u00fade do trabalhador.<\/h3>\n<h3 style=\"text-align: justify\">Na abertura \u00e0s 7 horas, acontece o Aul\u00e3o Azul Fitness, com show musical, dicas de sa\u00fade e exerc\u00edcios que valorizam a qualidade de vida. \u201cMais uma vez, Itabuna se uniu em torno dessa grande causa e vamos realizar um grande evento, que \u00e9 exemplo para o Brasil e replicado em quase 30 cidades em v\u00e1rios estados\u201d, afirma o Dr. Rafael Andrade, presidente da ONG Unidos pelo Diabetes e coordenador do Mutir\u00e3o.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 realizada neste s\u00e1bado, a 21\u00aa. edi\u00e7\u00e3o do Mutir\u00e3o do Diabetes de Itabuna, considerado um dos mais impactantes eventos de preven\u00e7\u00e3o e tratamento da doen\u00e7a da Am\u00e9rica Latina e que integra o calend\u00e1rio da Federa\u00e7\u00e3o Internacional do Diabetes. O mutir\u00e3o ter\u00e1 atendimento especializado no Hospital Beira Rio e a\u00e7\u00f5es de preven\u00e7\u00e3o na Cidade do Diabetes-Pra\u00e7a [&hellip;]<\/p>\n","protected":false},"author":992,"featured_media":194598,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"class_list":["post-194597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades"],"views":184,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194597"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/992"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=194597"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194597\/revisions"}],"predecessor-version":[{"id":194600,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194597\/revisions\/194600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/194598"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=194597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=194597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=194597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}