
{"id":194536,"date":"2025-11-08T10:40:12","date_gmt":"2025-11-08T13:40:12","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=194536"},"modified":"2025-11-08T10:40:12","modified_gmt":"2025-11-08T13:40:12","slug":"sandro-regis-celebra-chegada-de-nelson-leal-ex-presidente-da-assembleia-legislativa-a-base-de-acm-neto-o-movimento-de-mudanca-e-implacavel-na-bahia","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/11\/08\/sandro-regis-celebra-chegada-de-nelson-leal-ex-presidente-da-assembleia-legislativa-a-base-de-acm-neto-o-movimento-de-mudanca-e-implacavel-na-bahia\/","title":{"rendered":"SANDRO R\u00c9GIS CELEBRA CHEGADA DE NELSON LEAL, EX-PRESIDENTE DA ASSEMBLEIA LEGISLATIVA, \u00c0 BASE DE ACM NETO: \u201cO MOVIMENTO DE MUDAN\u00c7A \u00c9 IMPLAC\u00c1VEL NA BAHIA\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-194537 aligncenter\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-07-at-19.58.10.jpeg\" alt=\"\" width=\"455\" height=\"432\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-07-at-19.58.10.jpeg 455w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-07-at-19.58.10-300x285.jpeg 300w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/p>\n<h3 style=\"text-align: justify\">O deputado estadual Sandro R\u00e9gis (Uni\u00e3o Brasil) comemorou o an\u00fancio do ex-presidente da Assembleia Legislativa da Bahia, Nelson Leal (PP), que rompeu com o governo Jer\u00f4nimo Rodrigues (PT) e assumiu a coordena\u00e7\u00e3o da campanha de ACM Neto ao Governo da Bahia.<\/h3>\n<h3 style=\"text-align: justify\">Leal tamb\u00e9m anunciou que abrir\u00e1 m\u00e3o de disputar a reelei\u00e7\u00e3o para se dedicar integralmente \u00e0 nova fun\u00e7\u00e3o, em um movimento considerado estrat\u00e9gico para fortalecer o projeto oposicionista no estado.<\/h3>\n<h3 style=\"text-align: justify\">\u201cNelson Leal \u00e9 um grande amigo, um nome qualificado, grande articulador pol\u00edtico e uma lideran\u00e7a experiente e respeitada em toda a Bahia. A decis\u00e3o dele de abrir m\u00e3o do mandato para assumir essa miss\u00e3o mostra grandeza, coragem e compromisso com o futuro do nosso estado\u201d, disse Sandro R\u00e9gis.<\/h3>\n<h3 style=\"text-align: justify\">Para o deputado, a ades\u00e3o demonstra a for\u00e7a do movimento oposicionista. \u201cA chegada de Nelson confirma o que vemos em todo lugar: o movimento de mudan\u00e7a \u00e9 implac\u00e1vel na Bahia. Cada dia mais lideran\u00e7as entendem que o ciclo atual se esgotou e que a Bahia precisa de um novo caminho\u201d, completou.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Sandro R\u00e9gis (Uni\u00e3o Brasil) comemorou o an\u00fancio do ex-presidente da Assembleia Legislativa da Bahia, Nelson Leal (PP), que rompeu com o governo Jer\u00f4nimo Rodrigues (PT) e assumiu a coordena\u00e7\u00e3o da campanha de ACM Neto ao Governo da Bahia. Leal tamb\u00e9m anunciou que abrir\u00e1 m\u00e3o de disputar a reelei\u00e7\u00e3o para se dedicar integralmente [&hellip;]<\/p>\n","protected":false},"author":992,"featured_media":194537,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-194536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"views":217,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194536"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/992"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=194536"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194536\/revisions"}],"predecessor-version":[{"id":194538,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194536\/revisions\/194538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/194537"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=194536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=194536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=194536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}