
{"id":194362,"date":"2025-11-03T09:18:21","date_gmt":"2025-11-03T12:18:21","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=194362"},"modified":"2025-11-03T09:18:21","modified_gmt":"2025-11-03T12:18:21","slug":"coaraci-vence-mais-uma-e-segue-imbativel-no-intermunicipal","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/11\/03\/coaraci-vence-mais-uma-e-segue-imbativel-no-intermunicipal\/","title":{"rendered":"COARAC\u00cd VENCE MAIS UMA E SEGUE IMBAT\u00cdVEL NO INTERMUNICIPAL"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-194363\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/11\/1000026661-e1762172271932.webp\" alt=\"\" width=\"456\" height=\"325\" \/><\/p>\n<h3 style=\"text-align: justify;\">A sele\u00e7\u00e3o de Coarac\u00ed venceu neste domingo (02)) a sua 13\u00aa partida seguida no Campeonato Intermunicipal e continua com 100% de aproveitamento, somando 39 pontos. Jogando fora de casa pelas quartas definal, o time superou Santo Ant\u00f4nio de Jesus por 2&#215;0 e tem a vantagem de perder por at\u00e9 um gol de diferen\u00e7a em seu mando de campo.<\/p>\n<p>Os gols foram marcados pela dupla de ataque Nalberti e Coke, no segundo tempo. Nos acr\u00e9scimos, Coke chegou a marcar o terceiro gol para Coaraci, mas a arbitragem assinalou impedimento.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A sele\u00e7\u00e3o de Coarac\u00ed venceu neste domingo (02)) a sua 13\u00aa partida seguida no Campeonato Intermunicipal e continua com 100% de aproveitamento, somando 39 pontos. Jogando fora de casa pelas quartas definal, o time superou Santo Ant\u00f4nio de Jesus por 2&#215;0 e tem a vantagem de perder por at\u00e9 um gol de diferen\u00e7a em seu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":194363,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-194362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":159,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194362"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=194362"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194362\/revisions"}],"predecessor-version":[{"id":194364,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194362\/revisions\/194364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/194363"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=194362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=194362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=194362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}