
{"id":194233,"date":"2025-10-27T16:31:12","date_gmt":"2025-10-27T19:31:12","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=194233"},"modified":"2025-10-27T16:32:39","modified_gmt":"2025-10-27T19:32:39","slug":"ilheus-morre-perde-valerio-bomfim-agente-de-transito-e-lideranca-sindical","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/10\/27\/ilheus-morre-perde-valerio-bomfim-agente-de-transito-e-lideranca-sindical\/","title":{"rendered":"ILH\u00c9US: MORRE  VAL\u00c9RIO BOMFIM, AGENTE DE TR\u00c2NSITO E LIDERAN\u00c7A SINDICAL"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-194234\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/10\/34891presidente-de-sindicato-de-agentes-de-transito-causa-acidente-e-e-detido-por-embriaguez-ao-volante-3-e1761593423533.jpg\" alt=\"\" width=\"504\" height=\"309\" \/><\/p>\n<h3 style=\"text-align: justify;\">Faleceu nesta segunda-feira (27), em Salvador, o agente de tr\u00e2nsito Val\u00e9rio Bomfim Ribeiro, servidor da Prefeitura de Ilh\u00e9us, aos 51 anos. Ele estava internado no Instituto Couto Maia, unidade de refer\u00eancia no tratamento de doen\u00e7as infectocontagiosas, e foi v\u00edtima de uma infec\u00e7\u00e3o generalizada.<\/h3>\n<h3 style=\"text-align: justify;\">Figura conhecida e respeitada entre os colegas, Val\u00e9rio construiu uma trajet\u00f3ria marcada pelo comprometimento com o servi\u00e7o p\u00fablico e pela defesa da categoria dos agentes de tr\u00e2nsito. Atuante no movimento sindical, ele foi uma das principais vozes nas lutas por melhores condi\u00e7\u00f5es de trabalho, reconhecimento profissional e valoriza\u00e7\u00e3o salarial dos servidores municipais.<\/h3>\n<h3 style=\"text-align: justify;\">Colegas de profiss\u00e3o e representantes de entidades sindicais lamentaram a perda, destacando o esp\u00edrito de lideran\u00e7a, a dedica\u00e7\u00e3o e o senso de justi\u00e7a de Val\u00e9rio. \u201cEle foi uma refer\u00eancia na defesa da categoria, sempre conciliando firmeza nas reivindica\u00e7\u00f5es com respeito ao di\u00e1logo\u201d, afirmou um colega de trabalho.<\/h3>\n<p>O falecimento de Val\u00e9rio Bomfim deixa um vazio entre os servidores e sindicalistas de Ilh\u00e9us e da Bahia, onde seu nome se tornou s\u00edmbolo de luta e compromisso com o coletivo. A Prefeitura de Ilh\u00e9us e o sindicato dos agentes de tr\u00e2nsito devem emitir notas de pesar nas pr\u00f3ximas horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faleceu nesta segunda-feira (27), em Salvador, o agente de tr\u00e2nsito Val\u00e9rio Bomfim Ribeiro, servidor da Prefeitura de Ilh\u00e9us, aos 51 anos. Ele estava internado no Instituto Couto Maia, unidade de refer\u00eancia no tratamento de doen\u00e7as infectocontagiosas, e foi v\u00edtima de uma infec\u00e7\u00e3o generalizada. Figura conhecida e respeitada entre os colegas, Val\u00e9rio construiu uma trajet\u00f3ria marcada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":194234,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-194233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":150,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194233"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=194233"}],"version-history":[{"count":2,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194233\/revisions"}],"predecessor-version":[{"id":194236,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194233\/revisions\/194236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/194234"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=194233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=194233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=194233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}