
{"id":194198,"date":"2025-10-24T21:19:10","date_gmt":"2025-10-25T00:19:10","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=194198"},"modified":"2025-10-24T21:19:10","modified_gmt":"2025-10-25T00:19:10","slug":"valenca-deputado-federal-neto-carletto-ao-lado-de-leo-de-neco-destina-r-2-milhoes-em-emenda-para-a-santa-casa","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/10\/24\/valenca-deputado-federal-neto-carletto-ao-lado-de-leo-de-neco-destina-r-2-milhoes-em-emenda-para-a-santa-casa\/","title":{"rendered":"VALEN\u00c7A: DEPUTADO FEDERAL NETO CARLETTO, AO LADO DE L\u00c9O DE NECO, DESTINA R$ 2 MILH\u00d5ES EM EMENDA PARA A SANTA CASA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-194192\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-24-at-20.28.29.jpeg\" alt=\"\" width=\"450\" height=\"337\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-24-at-20.28.29.jpeg 450w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-24-at-20.28.29-300x225.jpeg 300w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-10-24-at-20.28.29-400x300.jpeg 400w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Em mais um gesto de compromisso com a sa\u00fade p\u00fablica e o fortalecimento da regi\u00e3o do Baixo Sul, o deputado federal Neto Carletto, ao lado do l\u00edder pol\u00edtico L\u00e9o de Neco, anunciou a destina\u00e7\u00e3o de uma emenda parlamentar no valor de R$ 2 milh\u00f5es para a Santa Casa de Valen\u00e7a.<\/h3>\n<h3 style=\"text-align: justify;\">Durante a visita \u00e0 institui\u00e7\u00e3o, acompanhados do provedor Marcelo e de toda a equipe da Santa Casa, os representantes conheceram de perto as instala\u00e7\u00f5es, dialogaram sobre as principais demandas e reafirmaram o compromisso de continuar buscando recursos e investimentos que melhorem o atendimento \u00e0 popula\u00e7\u00e3o.<\/h3>\n<h3 style=\"text-align: justify;\">A emenda parlamentar representa um importante refor\u00e7o para o hospital, que \u00e9 refer\u00eancia em atendimento m\u00e9dico e desempenha um papel fundamental no acolhimento e cuidado de pacientes n\u00e3o apenas de Valen\u00e7a, mas de todo o Baixo Sul.<\/h3>\n<h3 style=\"text-align: justify;\">\u201cEstamos muito felizes em poder contribuir com essa conquista. A Santa Casa tem uma fun\u00e7\u00e3o essencial no cuidado da nossa gente e merece todo o apoio poss\u00edvel para continuar prestando um servi\u00e7o de qualidade \u00e0 popula\u00e7\u00e3o\u201d, destacou L\u00e9o de Neco.<\/h3>\n<h3 style=\"text-align: justify;\">O deputado Neto Carletto refor\u00e7ou a import\u00e2ncia de investir na estrutura hospitalar e garantir melhores condi\u00e7\u00f5es de trabalho aos profissionais de sa\u00fade. \u201cEsse recurso \u00e9 mais um passo no fortalecimento da rede de sa\u00fade da regi\u00e3o. Nosso mandato est\u00e1 \u00e0 disposi\u00e7\u00e3o para continuar ajudando Valen\u00e7a e o Baixo Sul a avan\u00e7arem cada vez mais\u201d, afirmou.<\/p>\n<p>A Santa Casa de Valen\u00e7a \u00e9 um dos principais equipamentos de sa\u00fade da regi\u00e3o e tem sido fundamental no atendimento de m\u00e9dia e alta complexidade, oferecendo cuidado e dignidade a quem mais precisa.<br \/>\nA parceria entre Neto Carletto e L\u00e9o de Neco refor\u00e7a o compromisso de ambos com o desenvolvimento do Baixo Sul e com pol\u00edticas p\u00fablicas que priorizam o bem-estar da popula\u00e7\u00e3o.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Em mais um gesto de compromisso com a sa\u00fade p\u00fablica e o fortalecimento da regi\u00e3o do Baixo Sul, o deputado federal Neto Carletto, ao lado do l\u00edder pol\u00edtico L\u00e9o de Neco, anunciou a destina\u00e7\u00e3o de uma emenda parlamentar no valor de R$ 2 milh\u00f5es para a Santa Casa de Valen\u00e7a. Durante a visita \u00e0 institui\u00e7\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-194198","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":170,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194198"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=194198"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194198\/revisions"}],"predecessor-version":[{"id":194199,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/194198\/revisions\/194199"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=194198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=194198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=194198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}