
{"id":193916,"date":"2025-10-15T09:44:17","date_gmt":"2025-10-15T12:44:17","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=193916"},"modified":"2025-10-15T09:44:17","modified_gmt":"2025-10-15T12:44:17","slug":"porto-seguro-se-prepara-para-inaugurar-clinica-de-hemodialise-e-transformar-realidade-de-pacientes-moradores-e-turistas","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/10\/15\/porto-seguro-se-prepara-para-inaugurar-clinica-de-hemodialise-e-transformar-realidade-de-pacientes-moradores-e-turistas\/","title":{"rendered":"PORTO SEGURO SE PREPARA PARA INAUGURAR CL\u00cdNICA DE HEMODI\u00c1LISE E TRANSFORMAR REALIDADE DE PACIENTES MORADORES E TURISTAS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-193917\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/10\/560089374_24934613949503147_184293654576943896_n-e1760532224596.jpg\" alt=\"\" width=\"442\" height=\"783\" \/><\/p>\n<h3 style=\"text-align: justify;\">Moradores de Porto Seguro e turistas que dependem de tratamento de hemodi\u00e1lise ter\u00e3o um importante avan\u00e7o na \u00e1rea da sa\u00fade. A Prefeitura est\u00e1 finalizando a constru\u00e7\u00e3o da nova Cl\u00ednica de Hemodi\u00e1lise, um equipamento que promete melhorar significativamente a qualidade de vida de pacientes em estado cl\u00ednico sens\u00edvel, al\u00e9m de abrir novas possibilidades para o turismo na cidade.<\/h3>\n<h3 style=\"text-align: justify;\">Atualmente, quem precisa do tratamento enfrenta grandes desafios, incluindo deslocamentos para outros munic\u00edpios em busca de atendimento. A situa\u00e7\u00e3o atinge tanto moradores locais quanto visitantes, o que por muito tempo afastou pacientes em di\u00e1lise do destino tur\u00edstico.<\/h3>\n<h3 style=\"text-align: justify;\">O secret\u00e1rio de Turismo, Guto Jones, destacou o impacto da aus\u00eancia desse servi\u00e7o no setor: \u201cMuitos turistas deixavam de vir para Porto Seguro porque n\u00e3o havia assist\u00eancia de hemodi\u00e1lise. Isso impedia o crescimento do fluxo tur\u00edstico nesse p\u00fablico espec\u00edfico\u201d.<\/p>\n<p>J\u00e1 o prefeito J\u00e2nio Natal ressaltou o compromisso da gest\u00e3o com os pacientes. \u201cMesmo antes da cl\u00ednica, nunca deixamos esses pacientes desassistidos. O TFD (Tratamento Fora de Domic\u00edlio) sempre garantiu apoio. Mas \u00e9 desumano ter que viajar centenas de quil\u00f4metros em um estado de sa\u00fade delicado. A implanta\u00e7\u00e3o da hemodi\u00e1lise aqui sempre foi nossa prioridade\u201d, afirmou.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Moradores de Porto Seguro e turistas que dependem de tratamento de hemodi\u00e1lise ter\u00e3o um importante avan\u00e7o na \u00e1rea da sa\u00fade. A Prefeitura est\u00e1 finalizando a constru\u00e7\u00e3o da nova Cl\u00ednica de Hemodi\u00e1lise, um equipamento que promete melhorar significativamente a qualidade de vida de pacientes em estado cl\u00ednico sens\u00edvel, al\u00e9m de abrir novas possibilidades para o turismo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":193917,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-193916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":307,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193916"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=193916"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193916\/revisions"}],"predecessor-version":[{"id":193918,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193916\/revisions\/193918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/193917"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=193916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=193916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=193916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}