
{"id":193871,"date":"2025-10-13T11:57:06","date_gmt":"2025-10-13T14:57:06","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=193871"},"modified":"2025-10-13T11:57:06","modified_gmt":"2025-10-13T14:57:06","slug":"teixeira-de-freitas-joao-biquine-avaliar-ser-candidato-a-deputado","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/10\/13\/teixeira-de-freitas-joao-biquine-avaliar-ser-candidato-a-deputado\/","title":{"rendered":"TEIXEIRA DE FREITAS: JO\u00c3O BIQUINE AVALIAR SER CANDIDATO A DEPUTADO"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-193872\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/10\/563524674_24917421754555700_6952167232826889009_n.jpg\" alt=\"\" width=\"372\" height=\"545\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/10\/563524674_24917421754555700_6952167232826889009_n.jpg 372w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/10\/563524674_24917421754555700_6952167232826889009_n-205x300.jpg 205w\" sizes=\"(max-width: 372px) 100vw, 372px\" \/><\/p>\n<h3 style=\"text-align: justify;\">O ex-prefeito de Potiragu\u00e1, Jo\u00e3o Lisboa, conhecido popularmente como Jo\u00e3o Biquine, recebeu um convite do partido Republicanos para se filiar e disputar uma vaga de deputado estadual nas elei\u00e7\u00f5es de 2028. O convite foi feito pelo presidente estadual da sigla, deputado federal M\u00e1rcio Marinho (REP).<\/h3>\n<h3 style=\"text-align: justify;\">Com forte liga\u00e7\u00e3o ao setor agropecu\u00e1rio, Jo\u00e3o Biquine construiu trajet\u00f3ria de destaque em Teixeira de Freitas, atuando no ramo de frigor\u00edficos e como organizador de grandes vaquejadas, eventos tradicionais que movimentam o agroneg\u00f3cio e o turismo na regi\u00e3o.<\/h3>\n<h3 style=\"text-align: justify;\">Em contato com Jo\u00e3o Biquine , ele comentou que ainda avalia o convite, mas j\u00e1 sinalizou que pretende defender pautas ligadas ao agro e \u00e0 vaquejada, setores que fazem parte de sua hist\u00f3ria e identidade pol\u00edtica.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O ex-prefeito de Potiragu\u00e1, Jo\u00e3o Lisboa, conhecido popularmente como Jo\u00e3o Biquine, recebeu um convite do partido Republicanos para se filiar e disputar uma vaga de deputado estadual nas elei\u00e7\u00f5es de 2028. O convite foi feito pelo presidente estadual da sigla, deputado federal M\u00e1rcio Marinho (REP). Com forte liga\u00e7\u00e3o ao setor agropecu\u00e1rio, Jo\u00e3o Biquine construiu trajet\u00f3ria [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":193872,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-193871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":410,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193871"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=193871"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193871\/revisions"}],"predecessor-version":[{"id":193873,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193871\/revisions\/193873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/193872"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=193871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=193871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=193871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}