
{"id":193651,"date":"2025-10-01T11:29:02","date_gmt":"2025-10-01T14:29:02","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=193651"},"modified":"2025-10-01T11:29:02","modified_gmt":"2025-10-01T14:29:02","slug":"itapetinga-morre-ex-deputado-e-ex-prefeito-michel-hagge","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/10\/01\/itapetinga-morre-ex-deputado-e-ex-prefeito-michel-hagge\/","title":{"rendered":"ITAPETINGA: MORRE EX-DEPUTADO E EX-PREFEITO MICHEL HAGGE"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-193422\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/michel-hagge-itapetinga-1000x530-1-e1758495910508.jpg\" alt=\"\" width=\"500\" height=\"265\" \/><\/p>\n<h3 style=\"text-align: justify;\">Nesta quarta-feira (01), faleceu o ex-deputado estadual e ex-prefeito de Itapetinga, Michel Hagge (MDB), aos 97 anos. Ele estava internado em Vit\u00f3ria da Conquista desde o \u00faltimo dia 21 de setembro.<\/h3>\n<h3 style=\"text-align: justify;\">Figura hist\u00f3rica da pol\u00edtica baiana, Michel Hagge governou Itapetinga por tr\u00eas mandatos. Sua trajet\u00f3ria consolidou uma forte presen\u00e7a da fam\u00edlia na vida p\u00fablica do munic\u00edpio. Seu neto, Rodrigo Hagge, foi prefeito entre 2017 e 2024, e atualmente seu filho, Eduardo Hagge, ocupa o cargo de chefe do Executivo municipal. Ele foi eleito deputado por duas vezes.<\/p>\n<p>O falecimento encerra um ciclo de lideran\u00e7a marcado por quase sete d\u00e9cadas de atua\u00e7\u00e3o pol\u00edtica, deixando um legado de influ\u00eancia e representatividade na regi\u00e3o.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira (01), faleceu o ex-deputado estadual e ex-prefeito de Itapetinga, Michel Hagge (MDB), aos 97 anos. Ele estava internado em Vit\u00f3ria da Conquista desde o \u00faltimo dia 21 de setembro. Figura hist\u00f3rica da pol\u00edtica baiana, Michel Hagge governou Itapetinga por tr\u00eas mandatos. Sua trajet\u00f3ria consolidou uma forte presen\u00e7a da fam\u00edlia na vida p\u00fablica do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":193422,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-193651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":408,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193651"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=193651"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193651\/revisions"}],"predecessor-version":[{"id":193652,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193651\/revisions\/193652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/193422"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=193651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=193651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=193651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}