
{"id":193451,"date":"2025-09-22T22:49:22","date_gmt":"2025-09-23T01:49:22","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=193451"},"modified":"2025-09-22T22:49:22","modified_gmt":"2025-09-23T01:49:22","slug":"bahia-marcelo-emerenciano-proximo-de-se-filiar-ao-avante","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/09\/22\/bahia-marcelo-emerenciano-proximo-de-se-filiar-ao-avante\/","title":{"rendered":"BAHIA: MARCELO EMERENCIANO PR\u00d3XIMO DE SE FILIAR AO AVANTE"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-193452\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/537252793_18297855703247344_4661560332020213364_n-e1758592094803.jpg\" alt=\"\" width=\"500\" height=\"558\" \/><\/p>\n<h3 style=\"text-align: justify;\">O ex-prefeito de Cocos, Marcelo Emerenciano, poder\u00e1 deixar o PT para se filiar ao Avante. Atualmente, ele ocupa o cargo de assessor especial do ministro da Casa Civil, Rui Costa (PT).<\/h3>\n<h3 style=\"text-align: justify;\">Emerenciano j\u00e1 anunciou a inten\u00e7\u00e3o de disputar uma vaga de deputado federal e poder\u00e1 oficializar sua filia\u00e7\u00e3o no pr\u00f3ximo dia 6.<\/h3>\n<h3 style=\"text-align: justify;\">Outro que tamb\u00e9m deve seguir o mesmo caminho \u00e9 o ex-prefeito de Irec\u00ea, Elmo Vaz, que pretende se candidatar a deputado federal pela legenda.<\/p>\n<p>O presidente estadual do Avante, Ronaldo Carletto, tem intensificado as articula\u00e7\u00f5es para ampliar a bancada do partido na Bahia e fortalecer a sigla nas elei\u00e7\u00f5es de 2026, apostando na chegada de lideran\u00e7as regionais de peso.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O ex-prefeito de Cocos, Marcelo Emerenciano, poder\u00e1 deixar o PT para se filiar ao Avante. Atualmente, ele ocupa o cargo de assessor especial do ministro da Casa Civil, Rui Costa (PT). Emerenciano j\u00e1 anunciou a inten\u00e7\u00e3o de disputar uma vaga de deputado federal e poder\u00e1 oficializar sua filia\u00e7\u00e3o no pr\u00f3ximo dia 6. Outro que tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":193452,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-193451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":260,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193451"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=193451"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193451\/revisions"}],"predecessor-version":[{"id":193453,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193451\/revisions\/193453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/193452"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=193451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=193451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=193451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}