
{"id":193362,"date":"2025-09-17T22:13:57","date_gmt":"2025-09-18T01:13:57","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=193362"},"modified":"2025-09-17T22:13:57","modified_gmt":"2025-09-18T01:13:57","slug":"ilheus-mpf-suspende-obra-do-kahakai-beach-house-da-vca","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/09\/17\/ilheus-mpf-suspende-obra-do-kahakai-beach-house-da-vca\/","title":{"rendered":"ILH\u00c9US: MPF SUSPENDE OBRA DO KAHAKAI BEACH HOUSE DA VCA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-193363\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/LANCAMENTO-DO-KAHAKAI-BEACH-HOUSE-TRAZ-CONDOMINIOS-COM-ESTILO-DE-RESORT-PARA-ILHEUS-E-PORTO-SEGURO-768x432-1-e1758158012182.jpg\" alt=\"\" width=\"500\" height=\"281\" \/><\/p>\n<h3 style=\"text-align: justify;\">O Minist\u00e9rio P\u00fablico Federal (MPF) suspendeu o empreendimento Kahakai Beach House, da VCA Construtora, localizado na Estrada Una-Ilh\u00e9us (BA-001), em \u00c1guas de Oliven\u00e7a.<\/h3>\n<h3 style=\"text-align: justify;\">A decis\u00e3o integra inqu\u00e9rito conduzido pelo procurador da Rep\u00fablica Bruno Olivo de Sales, que apura a legalidade das autoriza\u00e7\u00f5es ambientais e patrimoniais. O MPF aponta ind\u00edcios de que o projeto foi instalado em \u00e1rea da Uni\u00e3o sem autoriza\u00e7\u00e3o da Secretaria do Patrim\u00f4nio da Uni\u00e3o (SPU) e cita poss\u00edveis irregularidades no licenciamento ambiental.<\/h3>\n<h3 style=\"text-align: justify;\">Um laudo pericial indicou inconsist\u00eancias nos estudos ambientais apresentados ao Instituto do Meio Ambiente e Recursos H\u00eddricos da Bahia (INEMA). O MPF j\u00e1 havia questionado a validade jur\u00eddica do parecer do \u00f3rg\u00e3o, mas n\u00e3o obteve resposta.<\/p>\n<p>A VCA Construtora informou ter sido surpreendida com a decis\u00e3o e disse que est\u00e1 adotando medidas para liberar a obra.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico Federal (MPF) suspendeu o empreendimento Kahakai Beach House, da VCA Construtora, localizado na Estrada Una-Ilh\u00e9us (BA-001), em \u00c1guas de Oliven\u00e7a. A decis\u00e3o integra inqu\u00e9rito conduzido pelo procurador da Rep\u00fablica Bruno Olivo de Sales, que apura a legalidade das autoriza\u00e7\u00f5es ambientais e patrimoniais. O MPF aponta ind\u00edcios de que o projeto foi instalado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":193363,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-193362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":540,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193362"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=193362"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193362\/revisions"}],"predecessor-version":[{"id":193364,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193362\/revisions\/193364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/193363"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=193362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=193362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=193362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}