
{"id":193291,"date":"2025-09-15T10:34:20","date_gmt":"2025-09-15T13:34:20","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=193291"},"modified":"2025-09-15T10:34:20","modified_gmt":"2025-09-15T13:34:20","slug":"bahia-aleluia-comente-erro-de-acm-neto-em-entrevista-ao-frequencia-politica","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/09\/15\/bahia-aleluia-comente-erro-de-acm-neto-em-entrevista-ao-frequencia-politica\/","title":{"rendered":"BAHIA: ALELUIA COMENTE ERRO DE  ACM NETO EM ENTREVISTA AO FREQU\u00caNCIA POL\u00cdTICA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-193292\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/aleluiaaaa-e1757943232447.jpg\" alt=\"\" width=\"500\" height=\"333\" \/><\/p>\n<h3 style=\"text-align: justify;\">No \u00faltimo s\u00e1bado, o pr\u00e9-candidato ao governo da Bahia, Aleluia (NOVO), concedeu entrevista ao programa Frequ\u00eancia Pol\u00edtica, transmitido em rede pelas r\u00e1dios Interativa FM, Difusora AM e Itapuy FM. Durante a conversa, ele foi questionado pelo analista pol\u00edtico Jo\u00e3o Matheus sobre os erros cometidos pelo ex-prefeito de Salvador, ACM Neto, nas elei\u00e7\u00f5es de 2022.<\/h3>\n<h3 style=\"text-align: justify;\">Aleluia resgatou fatos hist\u00f3ricos para embasar sua an\u00e1lise. Segundo ele, a trajet\u00f3ria pol\u00edtica da fam\u00edlia ACM mostra escolhas equivocadas em momentos decisivos:<\/h3>\n<h3 style=\"text-align: justify;\">\u201cEm 2002, ACM fez um acordo com Z\u00e9 Dirceu para Lula n\u00e3o fazer campanha na Bahia. No acordo, ACM apoiou Lula no segundo turno contra Serra. Foi um p\u00e9ssimo acordo, j\u00e1 que em 2006 Lula fez Wagner governador da Bahia contra o grupo de ACM. J\u00e1 ACM Neto errou em n\u00e3o apoiar Bolsonaro em 2022. Se n\u00e3o tivesse elei\u00e7\u00e3o na Bahia, Bolsonaro teria sido reeleito. A diferen\u00e7a de Lula na Bahia foi quase a diferen\u00e7a que deu a vit\u00f3ria a Lula no Brasil. O erro de ACM Neto foi n\u00e3o apoiar Bolsonaro.\u201d<\/p>\n<p>A declara\u00e7\u00e3o refor\u00e7a a cr\u00edtica do pr\u00e9-candidato \u00e0 postura adotada por ACM Neto nas \u00faltimas elei\u00e7\u00f5es e projeta o debate sobre os rumos da oposi\u00e7\u00e3o no estado, especialmente no cen\u00e1rio que se desenha para 2026.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo s\u00e1bado, o pr\u00e9-candidato ao governo da Bahia, Aleluia (NOVO), concedeu entrevista ao programa Frequ\u00eancia Pol\u00edtica, transmitido em rede pelas r\u00e1dios Interativa FM, Difusora AM e Itapuy FM. Durante a conversa, ele foi questionado pelo analista pol\u00edtico Jo\u00e3o Matheus sobre os erros cometidos pelo ex-prefeito de Salvador, ACM Neto, nas elei\u00e7\u00f5es de 2022. Aleluia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":193292,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-193291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":159,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193291"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=193291"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193291\/revisions"}],"predecessor-version":[{"id":193293,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193291\/revisions\/193293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/193292"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=193291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=193291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=193291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}