
{"id":193235,"date":"2025-09-11T10:33:06","date_gmt":"2025-09-11T13:33:06","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=193235"},"modified":"2025-09-11T10:33:06","modified_gmt":"2025-09-11T13:33:06","slug":"ibicarai-oposicao-reclama-de-distanciamento-de-demetrio-castro-e-acusa-aproximacao-com-base-governista","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/09\/11\/ibicarai-oposicao-reclama-de-distanciamento-de-demetrio-castro-e-acusa-aproximacao-com-base-governista\/","title":{"rendered":"IBICARA\u00cd: OPOSI\u00c7\u00c3O RECLAMA DE DISTANCIAMENTO DE DEM\u00c9TRIO CASTRO E ACUSA APROXIMA\u00c7\u00c3O COM BASE GOVERNISTA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-193236\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/545709049_3727225657414380_6960671351405133594_n-e1757597555185.jpg\" alt=\"\" width=\"450\" height=\"678\" \/><\/p>\n<h3 style=\"text-align: justify;\">O clima pol\u00edtico na C\u00e2mara de Vereadores de Ibicara\u00ed tem se acirrado nos \u00faltimos dias. Parlamentares da oposi\u00e7\u00e3o demonstraram insatisfa\u00e7\u00e3o com a postura do vereador Dem\u00e9trio Castro (PSDB), que, segundo eles, estaria se afastando das pautas oposicionistas e se aproximando da base governista.<\/h3>\n<h3 style=\"text-align: justify;\">Na sess\u00e3o desta quarta-feira (10), a aus\u00eancia de Dem\u00e9trio Castro, que n\u00e3o compareceu junto com os cinco vereadores ligados ao governo municipal, impediu que a oposi\u00e7\u00e3o tivesse qu\u00f3rum suficiente para convocar a secret\u00e1ria de Finan\u00e7as da cidade. A situa\u00e7\u00e3o gerou ainda mais desconforto entre os colegas oposicionistas.<\/h3>\n<h3 style=\"text-align: justify;\">O vereador, no entanto, tem evitado se posicionar publicamente sobre seu alinhamento pol\u00edtico. Nas redes sociais, adotou uma postura mais introspectiva, limitando publica\u00e7\u00f5es e intera\u00e7\u00f5es.<\/h3>\n<h3 style=\"text-align: justify;\">Segundo uma fonte ligada ao legislativo, a Mesa Diretora da C\u00e2mara teria tomado medidas de restri\u00e7\u00e3o contra Dem\u00e9trio, reduzindo alguns de seus espa\u00e7os e deixando-o em situa\u00e7\u00e3o de \u201ccanela seca\u201d, express\u00e3o usada nos bastidores pol\u00edticos para indicar isolamento ou perda de privil\u00e9gios.<\/p>\n<p>A movimenta\u00e7\u00e3o de Dem\u00e9trio Castro segue em observa\u00e7\u00e3o pelos dois lados da Casa, podendo definir novos rumos na correla\u00e7\u00e3o de for\u00e7as pol\u00edticas do munic\u00edpio.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O clima pol\u00edtico na C\u00e2mara de Vereadores de Ibicara\u00ed tem se acirrado nos \u00faltimos dias. Parlamentares da oposi\u00e7\u00e3o demonstraram insatisfa\u00e7\u00e3o com a postura do vereador Dem\u00e9trio Castro (PSDB), que, segundo eles, estaria se afastando das pautas oposicionistas e se aproximando da base governista. Na sess\u00e3o desta quarta-feira (10), a aus\u00eancia de Dem\u00e9trio Castro, que n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":193236,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-193235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":266,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193235"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=193235"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193235\/revisions"}],"predecessor-version":[{"id":193237,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193235\/revisions\/193237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/193236"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=193235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=193235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=193235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}