
{"id":193149,"date":"2025-09-09T09:25:06","date_gmt":"2025-09-09T12:25:06","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=193149"},"modified":"2025-09-09T09:25:06","modified_gmt":"2025-09-09T12:25:06","slug":"eunapolis-ao-lado-de-claudia-e-roberio-jeronimo-anuncia-elevacao-da-7a-cipm-para-batalhao-da-pm-reajuste-salarial-para-policiais","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/09\/09\/eunapolis-ao-lado-de-claudia-e-roberio-jeronimo-anuncia-elevacao-da-7a-cipm-para-batalhao-da-pm-reajuste-salarial-para-policiais\/","title":{"rendered":"EUN\u00c1POLIS: AO LADO DE CL\u00c1UDIA E ROB\u00c9RIO, JER\u00d4NIMO ANUNCIA ELEVA\u00c7\u00c3O DA 7\u00aa CIPM PARA BATALH\u00c3O DA PM REAJUSTE SALARIAL PARA POLICIAIS"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-193150 aligncenter\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-08-at-22.44.55.jpeg\" alt=\"\" width=\"455\" height=\"360\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-08-at-22.44.55.jpeg 1136w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-08-at-22.44.55-300x237.jpeg 300w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-08-at-22.44.55-1024x809.jpeg 1024w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-08-at-22.44.55-768x607.jpeg 768w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/p>\n<h4 style=\"text-align: center\">Novo batalh\u00e3o \u00e9 fruto de uma indica\u00e7\u00e3o feita pelo mandato da deputada Cl\u00e1udia Oliveira, para fortalecer a seguran\u00e7a p\u00fablica na regi\u00e3o<\/h4>\n<h3 style=\"text-align: justify\">O governador Jer\u00f4nimo Rodrigues (PT) anunciou nesta segunda-feira (8), ao lado da deputada estadual Cl\u00e1udia Oliveira (PSD) e do prefeito Rob\u00e9rio Oliveira, a eleva\u00e7\u00e3o da 7\u00aa Companhia Independente da Pol\u00edcia Militar (CIPM) \u00e0 condi\u00e7\u00e3o de Batalh\u00e3o da PM em Eun\u00e1polis.<\/h3>\n<h3 style=\"text-align: justify\">A medida faz parte da reestrutura\u00e7\u00e3o das for\u00e7as de seguran\u00e7a da Bahia, que prev\u00ea a cria\u00e7\u00e3o de 14 novas unidades da Pol\u00edcia Militar em diferentes cidades do estado. Com a mudan\u00e7a, Eun\u00e1polis passar\u00e1 a contar com um efetivo maior, aumento do n\u00famero de oficiais e uma estrutura administrativa mais robusta. A transforma\u00e7\u00e3o da companhia em batalh\u00e3o garante maior capacidade operacional e mais agilidade no combate \u00e0 criminalidade na regi\u00e3o.<\/h3>\n<h3 style=\"text-align: justify\">Durante o evento, realizado no Centro Administrativo da Bahia, Jer\u00f4nimo tamb\u00e9m anunciou um reajuste salarial para os profissionais da seguran\u00e7a p\u00fablica. A Pol\u00edcia Militar ser\u00e1 contemplada com um aumento de 13,63%, enquanto a Pol\u00edcia Civil ter\u00e1 reajuste de 22% e o sistema penitenci\u00e1rio, de 13,39%.<\/h3>\n<h3 style=\"text-align: justify\">A deputada estadual Cl\u00e1udia Oliveira celebrou a conquista: \u201cEssa \u00e9 uma luta antiga nossa. A transforma\u00e7\u00e3o da companhia em batalh\u00e3o representa mais seguran\u00e7a, mais respeito e mais estrutura para nossos policiais e para a popula\u00e7\u00e3o.\u201d<\/h3>\n<h3 style=\"text-align: justify\">J\u00e1 o prefeito Rob\u00e9rio Oliveira destacou o impacto direto na vida dos moradores: \u201cA cidade ganha muito com esse refor\u00e7o. Essa \u00e9 uma conquista importante que vai garantir mais tranquilidade para as fam\u00edlias eunapolitanas e mais condi\u00e7\u00f5es de trabalho para a Pol\u00edcia Militar. Seguimos trabalhando por Eun\u00e1polis.\u201d<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Novo batalh\u00e3o \u00e9 fruto de uma indica\u00e7\u00e3o feita pelo mandato da deputada Cl\u00e1udia Oliveira, para fortalecer a seguran\u00e7a p\u00fablica na regi\u00e3o O governador Jer\u00f4nimo Rodrigues (PT) anunciou nesta segunda-feira (8), ao lado da deputada estadual Cl\u00e1udia Oliveira (PSD) e do prefeito Rob\u00e9rio Oliveira, a eleva\u00e7\u00e3o da 7\u00aa Companhia Independente da Pol\u00edcia Militar (CIPM) \u00e0 [&hellip;]<\/p>\n","protected":false},"author":992,"featured_media":193150,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"class_list":["post-193149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades"],"views":193,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193149"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/992"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=193149"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193149\/revisions"}],"predecessor-version":[{"id":193151,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193149\/revisions\/193151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/193150"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=193149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=193149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=193149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}