
{"id":193099,"date":"2025-09-06T21:53:18","date_gmt":"2025-09-07T00:53:18","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=193099"},"modified":"2025-09-06T21:53:18","modified_gmt":"2025-09-07T00:53:18","slug":"potiragua-prefeito-elias-carvalho-recebe-liderancas-politicas-na-festa-de-vaquejada","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/09\/06\/potiragua-prefeito-elias-carvalho-recebe-liderancas-politicas-na-festa-de-vaquejada\/","title":{"rendered":"POTIRAGU\u00c1: PREFEITO ELIAS CARVALHO RECEBE LIDERAN\u00c7AS POL\u00cdTICAS NA FESTA DE VAQUEJADA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-193100\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/09\/20250905_210340-e1757206372465.jpg\" alt=\"\" width=\"500\" height=\"375\" \/><\/p>\n<h3 style=\"text-align: justify;\">O prefeito de Potiragu\u00e1, Elias Carvalho, reuniu nesta sexta-feira (05) importantes lideran\u00e7as pol\u00edticas da regi\u00e3o em uma s\u00e9rie de atividades no munic\u00edpio.<\/h3>\n<h3 style=\"text-align: justify;\">Entre os presentes estiveram o prefeito de Itabuna, Augusto Castro, acompanhado da esposa e pr\u00e9-candidata a deputada estadual, Andrea Castro, al\u00e9m do presidente estadual do Avante, Ronaldo Carletto, que representou o deputado federal Neto Carletto.<\/h3>\n<h3 style=\"text-align: justify;\">A agenda incluiu a participa\u00e7\u00e3o dos ex-prefeitos Salvador Brito e Jorge Cheles, vereadores e secret\u00e1rios municipais, que acompanharam Elias em uma carreata pelas ruas da cidade. O encontro foi encerrado com um jantar de confraterniza\u00e7\u00e3o.<\/p>\n<p>Na sequ\u00eancia, as autoridades prestigiaram a tradicional Festa de Vaquejada, um dos maiores eventos do munic\u00edpio, refor\u00e7ando o prest\u00edgio pol\u00edtico e social do momento.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Potiragu\u00e1, Elias Carvalho, reuniu nesta sexta-feira (05) importantes lideran\u00e7as pol\u00edticas da regi\u00e3o em uma s\u00e9rie de atividades no munic\u00edpio. Entre os presentes estiveram o prefeito de Itabuna, Augusto Castro, acompanhado da esposa e pr\u00e9-candidata a deputada estadual, Andrea Castro, al\u00e9m do presidente estadual do Avante, Ronaldo Carletto, que representou o deputado federal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":193100,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-193099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":191,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193099"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=193099"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193099\/revisions"}],"predecessor-version":[{"id":193101,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/193099\/revisions\/193101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/193100"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=193099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=193099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=193099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}