
{"id":192881,"date":"2025-08-28T16:09:00","date_gmt":"2025-08-28T19:09:00","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=192881"},"modified":"2025-08-28T16:09:00","modified_gmt":"2025-08-28T19:09:00","slug":"itabuna-pcdob-assume-secretaria-de-planejamento-com-nomeacao-de-kiko","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/08\/28\/itabuna-pcdob-assume-secretaria-de-planejamento-com-nomeacao-de-kiko\/","title":{"rendered":"ITABUNA: PCDOB ASSUME SECRETARIA DE PLANEJAMENTO COM NOMEA\u00c7\u00c3O DE KIKO"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-192882\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/539839722_24509432978687915_7976985497678073756_n-e1756408094894.jpg\" alt=\"\" width=\"450\" height=\"477\" \/><\/p>\n<h3 style=\"text-align: justify;\">O Partido Comunista do Brasil (PCdoB) conquistou um espa\u00e7o estrat\u00e9gico na gest\u00e3o do prefeito Augusto Castro (PSD) em Itabuna. Ap\u00f3s conversas pol\u00edticas que vinham sendo alinhadas nas \u00faltimas semanas, o militante hist\u00f3rico da legenda, Marcos Alves de Souza, o Kiko, foi confirmado como o novo secret\u00e1rio municipal de Planejamento.<\/h3>\n<h3 style=\"text-align: justify;\">A posse deve ocorrer nos pr\u00f3ximos dias, colocando Kiko em um dos cargos de primeiro escal\u00e3o mais importantes da administra\u00e7\u00e3o. A pasta \u00e9 respons\u00e1vel por articular projetos estruturantes e planejar o desenvolvimento da cidade, atuando diretamente nas pol\u00edticas p\u00fablicas de m\u00e9dio e longo prazo.<\/h3>\n<h3 style=\"text-align: justify;\">O presidente do diret\u00f3rio municipal do PCdoB em Itabuna, Jorge Barbosa de Jesus, celebrou a indica\u00e7\u00e3o:<\/h3>\n<h3 style=\"text-align: justify;\">\u201cTemos certeza que a compet\u00eancia e dedica\u00e7\u00e3o do camarada Kiko contribuir\u00e3o para a boa gest\u00e3o do nosso amado munic\u00edpio. Ao trabalho! Desejamos inteiro sucesso!\u201d, destacou.<\/p>\n<p>A entrada do PCdoB no governo refor\u00e7a a base de sustenta\u00e7\u00e3o pol\u00edtica do prefeito Augusto Castro e sinaliza o fortalecimento do di\u00e1logo entre o Executivo e os partidos de esquerda no munic\u00edpio.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O Partido Comunista do Brasil (PCdoB) conquistou um espa\u00e7o estrat\u00e9gico na gest\u00e3o do prefeito Augusto Castro (PSD) em Itabuna. Ap\u00f3s conversas pol\u00edticas que vinham sendo alinhadas nas \u00faltimas semanas, o militante hist\u00f3rico da legenda, Marcos Alves de Souza, o Kiko, foi confirmado como o novo secret\u00e1rio municipal de Planejamento. A posse deve ocorrer nos pr\u00f3ximos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":192882,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-192881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":262,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192881"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=192881"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192881\/revisions"}],"predecessor-version":[{"id":192883,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192881\/revisions\/192883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/192882"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=192881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=192881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=192881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}