
{"id":192828,"date":"2025-08-27T12:15:04","date_gmt":"2025-08-27T15:15:04","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=192828"},"modified":"2025-08-27T12:15:04","modified_gmt":"2025-08-27T15:15:04","slug":"itabuna-6a-edicao-do-final-de-semana-do-produtor-da-adasb-promete-megaevento","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/08\/27\/itabuna-6a-edicao-do-final-de-semana-do-produtor-da-adasb-promete-megaevento\/","title":{"rendered":"ITABUNA: 6\u00aa EDI\u00c7\u00c3O DO FINAL DE SEMANA DO PRODUTOR DA ADASB PROMETE MEGAEVENTO"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-192829\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/6o-Final-de-Semana-do-Produtor-Rural-ADASB.jpg\" alt=\"\" width=\"450\" height=\"563\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/6o-Final-de-Semana-do-Produtor-Rural-ADASB.jpg 450w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/6o-Final-de-Semana-do-Produtor-Rural-ADASB-240x300.jpg 240w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Itabuna se prepara para sediar um megaevento do Agro entre os dias 08 e 12 de Outubro, no Espora de Ouro. O evento, batizado pela Associa\u00e7\u00e3o dos Agropecuaristas do Sul da Bahia (ADASB) como \u201cFinal de Semana do Produtor Rural\u201d est\u00e1 na sua 6\u00aa Edi\u00e7\u00e3o e promete novidades e uma estrutura que ir\u00e1 superar as edi\u00e7\u00f5es anteriores.<\/h3>\n<h3 style=\"text-align: justify;\">Com o slogan \u201cNossa Terra, Nosso Orgulho\u201d, a festa est\u00e1 sendo preparada com muito empenho e dedica\u00e7\u00e3o pela Associa\u00e7\u00e3o dos Agropecuaristas do Sul da Bahia. O presidente da ADASB, Aldrin Trevisan, ressalta que a expectativa \u00e9 que o evento seja mais uma vez reconhecido como a festa do Agro Regional.<\/h3>\n<h3 style=\"text-align: justify;\">\u201cA ADASB conseguiu ao longo dos anos mostrar o seu potencial como organizadora de um evento que \u00e9 t\u00e3o importante para a economia regional, e a prova disso \u00e9 o apoio da Prefeitura de Itabuna pelo terceiro ano consecutivo. Temos tamb\u00e9m o apoio da CDL, do vereador Erasmo \u00c1vila, da Rancho Leil\u00f5es, entre outros parceiros\u201d, frisa Aldrin Trevisan.<\/h3>\n<h3 style=\"text-align: justify;\">Exposi\u00e7\u00e3o do MangaLarga Marchador, Arena de Neg\u00f3cios, Espa\u00e7o Gastron\u00f4mico, expositores de diversos segmentos comerciais, som ao vivo, divers\u00e3o para a garotada com parque infantil e anima\u00e7\u00e3o s\u00e3o alguns dos atrativos desta festa que est\u00e1 sendo preparada para toda fam\u00edlia!<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Itabuna se prepara para sediar um megaevento do Agro entre os dias 08 e 12 de Outubro, no Espora de Ouro. O evento, batizado pela Associa\u00e7\u00e3o dos Agropecuaristas do Sul da Bahia (ADASB) como \u201cFinal de Semana do Produtor Rural\u201d est\u00e1 na sua 6\u00aa Edi\u00e7\u00e3o e promete novidades e uma estrutura que ir\u00e1 superar as [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":192829,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-192828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":222,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192828"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=192828"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192828\/revisions"}],"predecessor-version":[{"id":192830,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192828\/revisions\/192830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/192829"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=192828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=192828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=192828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}