
{"id":192505,"date":"2025-08-13T13:51:13","date_gmt":"2025-08-13T16:51:13","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=192505"},"modified":"2025-08-13T13:51:13","modified_gmt":"2025-08-13T16:51:13","slug":"floresta-azul-prefeito-deve-anunciar-novos-deputados","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/08\/13\/floresta-azul-prefeito-deve-anunciar-novos-deputados\/","title":{"rendered":"FLORESTA AZUL: PREFEITO  DEVE ANUNCIAR NOVOS DEPUTADOS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-192506\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-13-134327.png\" alt=\"\" width=\"350\" height=\"285\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-13-134327.png 350w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-13-134327-300x244.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/p>\n<h3 style=\"text-align: justify;\">O prefeito de Floresta Azul, Bambu(PSB), vai anunciar na pr\u00f3xima sexta-feira (16) os nomes dos deputados que receber\u00e3o seu apoio pol\u00edtico. A decis\u00e3o vem ap\u00f3s o rompimento com o grupo do ex-prefeito Garraf\u00e3o (PSB), o que levou o gestor a redefinir suas alian\u00e7as.<\/h3>\n<h3 style=\"text-align: justify;\">Segundo apura\u00e7\u00e3o do site, Bambu j\u00e1 escolheu como deputado federal o experiente Paulo Magalh\u00e3es (PSD). Para a vaga de deputado estadual, o nome mais cotado \u00e9 o de Marcone Amaral (PSD), que contaria com o aval do pr\u00f3prio Paulo Magalh\u00e3es.<\/p>\n<p>Com a mudan\u00e7a, o grupo do ex-prefeito Garraf\u00e3o deve manter apoio ao deputado estadual Rosemberg Pinto (PT) e ao deputado federal Neto Carletto (Avante), configurando um novo cen\u00e1rio pol\u00edtico na cidade e reorganizando os blocos de apoio para as pr\u00f3ximas disputas eleitorais.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Floresta Azul, Bambu(PSB), vai anunciar na pr\u00f3xima sexta-feira (16) os nomes dos deputados que receber\u00e3o seu apoio pol\u00edtico. A decis\u00e3o vem ap\u00f3s o rompimento com o grupo do ex-prefeito Garraf\u00e3o (PSB), o que levou o gestor a redefinir suas alian\u00e7as. Segundo apura\u00e7\u00e3o do site, Bambu j\u00e1 escolheu como deputado federal o experiente [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":192506,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-192505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":224,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192505"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=192505"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192505\/revisions"}],"predecessor-version":[{"id":192507,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192505\/revisions\/192507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/192506"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=192505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=192505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=192505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}