
{"id":192326,"date":"2025-08-07T10:14:33","date_gmt":"2025-08-07T13:14:33","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=192326"},"modified":"2025-08-07T10:14:33","modified_gmt":"2025-08-07T13:14:33","slug":"itapetinga-camara-abre-cpi-para-investigar-oficio-supostamente-falsificado","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/08\/07\/itapetinga-camara-abre-cpi-para-investigar-oficio-supostamente-falsificado\/","title":{"rendered":"ITAPETINGA: C\u00c2MARA ABRE CPI PARA INVESTIGAR OF\u00cdCIO SUPOSTAMENTE FALSIFICADO"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-192327\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/515438776_24325954327035782_585612023417454005_n-e1754572427567.jpg\" alt=\"\" width=\"450\" height=\"713\" \/><\/p>\n<h3 style=\"text-align: justify;\">A C\u00e2mara de Vereadores de Itapetinga pretende instaurar uma Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) para apurar a poss\u00edvel falsifica\u00e7\u00e3o de um of\u00edcio protocolado na Governadoria do Estado. O documento em quest\u00e3o solicita acompanhamento de um processo eleitoral que trata da cassa\u00e7\u00e3o do diploma do vereador Diego Queiroz Rodrigues, conhecido como Diga Diga.<\/h3>\n<h3 style=\"text-align: justify;\">Segundo apura\u00e7\u00e3o do site, o prefeito Eduardo Hagge n\u00e3o reconhece o of\u00edcio como aut\u00eantico. Diante da suspeita de falsifica\u00e7\u00e3o e do uso indevido do nome da Prefeitura, 11 dos 15 vereadores assinaram um requerimento pedindo a abertura da CPI. O objetivo \u00e9 identificar os respons\u00e1veis pela elabora\u00e7\u00e3o e envio do suposto documento falso.<\/p>\n<p>A expectativa \u00e9 de que a investiga\u00e7\u00e3o seja iniciada nos pr\u00f3ximos dias, com a oitiva de servidores, an\u00e1lise de documentos e eventual responsabiliza\u00e7\u00e3o dos envolvidos. O caso j\u00e1 repercute fortemente nos bastidores da pol\u00edtica local.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara de Vereadores de Itapetinga pretende instaurar uma Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) para apurar a poss\u00edvel falsifica\u00e7\u00e3o de um of\u00edcio protocolado na Governadoria do Estado. O documento em quest\u00e3o solicita acompanhamento de um processo eleitoral que trata da cassa\u00e7\u00e3o do diploma do vereador Diego Queiroz Rodrigues, conhecido como Diga Diga. Segundo apura\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":192327,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-192326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":252,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192326"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=192326"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192326\/revisions"}],"predecessor-version":[{"id":192328,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192326\/revisions\/192328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/192327"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=192326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=192326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=192326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}