
{"id":192323,"date":"2025-08-07T10:03:26","date_gmt":"2025-08-07T13:03:26","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=192323"},"modified":"2025-08-07T10:03:26","modified_gmt":"2025-08-07T13:03:26","slug":"brumado-formacao-continuada-para-mediadores-do-tempo-integral-fortalece-praticas-de-aprendizagem-na-rede-municipal","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/08\/07\/brumado-formacao-continuada-para-mediadores-do-tempo-integral-fortalece-praticas-de-aprendizagem-na-rede-municipal\/","title":{"rendered":"BRUMADO: FORMA\u00c7\u00c3O CONTINUADA PARA MEDIADORES DO TEMPO INTEGRAL FORTALECE PR\u00c1TICAS DE APRENDIZAGEM NA REDE MUNICIPAL"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-192324\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/3344-img_2128.jpg\" alt=\"\" width=\"450\" height=\"338\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/3344-img_2128.jpg 450w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/3344-img_2128-300x225.jpg 300w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/3344-img_2128-400x300.jpg 400w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Com o objetivo de qualificar ainda mais os profissionais que atuam no ensino de Tempo Integral, a Prefeitura de Brumado, por meio da Secretaria Municipal de Educa\u00e7\u00e3o (SEMEC), em parceria com o Sebrae, promoveu, nesta segunda (04) e ter\u00e7a-feira (05), uma forma\u00e7\u00e3o continuada voltada aos mediadores das escolas municipais Nice P\u00fablio e Oscarlina Oliveira.<\/h3>\n<h3 style=\"text-align: justify;\">A forma\u00e7\u00e3o, que contou com oficinas e palestras ministradas por oficineiros convidados, integra o curso de Comunica\u00e7\u00e3o e Marketing voltado ao contexto escolar. A proposta busca fortalecer a media\u00e7\u00e3o pedag\u00f3gica em sala de aula, promover a recomposi\u00e7\u00e3o das aprendizagens e consolidar as habilidades e compet\u00eancias exigidas pelas Avalia\u00e7\u00f5es Externas.<\/h3>\n<h3 style=\"text-align: justify;\">A coordenadora do Ensino Fundamental II, Ana Gama, que tamb\u00e9m \u00e9 professora e mestra da Rede Municipal, destacou a import\u00e2ncia de iniciativas como esta para o avan\u00e7o da qualidade do ensino. \u201cEstamos em constante di\u00e1logo com a secret\u00e1ria Ana Cristina, fomentando e criando espa\u00e7os de forma\u00e7\u00e3o continuada para gestores, coordenadores e toda a equipe pedag\u00f3gica. Nosso compromisso \u00e9 multiplicar conhecimento em cada escola, impactando diretamente na aprendizagem dos estudantes\u201d, afirmou.<\/h3>\n<h3 style=\"text-align: justify;\">A a\u00e7\u00e3o refor\u00e7a o compromisso da gest\u00e3o com a valoriza\u00e7\u00e3o dos profissionais da educa\u00e7\u00e3o e com a oferta de uma educa\u00e7\u00e3o p\u00fablica cada vez mais qualificada, que atenda \u00e0s reais necessidades dos alunos em tempo integral.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de qualificar ainda mais os profissionais que atuam no ensino de Tempo Integral, a Prefeitura de Brumado, por meio da Secretaria Municipal de Educa\u00e7\u00e3o (SEMEC), em parceria com o Sebrae, promoveu, nesta segunda (04) e ter\u00e7a-feira (05), uma forma\u00e7\u00e3o continuada voltada aos mediadores das escolas municipais Nice P\u00fablio e Oscarlina Oliveira. A [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":192324,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-192323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":172,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192323"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=192323"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192323\/revisions"}],"predecessor-version":[{"id":192325,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192323\/revisions\/192325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/192324"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=192323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=192323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=192323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}