
{"id":192277,"date":"2025-08-05T19:48:17","date_gmt":"2025-08-05T22:48:17","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=192277"},"modified":"2025-08-05T19:48:17","modified_gmt":"2025-08-05T22:48:17","slug":"eunapolis-inscricoes-abertas-para-o-projeto-tocar-encantar","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/08\/05\/eunapolis-inscricoes-abertas-para-o-projeto-tocar-encantar\/","title":{"rendered":"EUN\u00c1POLIS : INSCRI\u00c7\u00d5ES ABERTAS PARA O PROJETO \u201cTOCAR &#038; ENCANTAR\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-192278\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/Projeto-tocar-e-encantar.jpg\" alt=\"\" width=\"450\" height=\"600\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/Projeto-tocar-e-encantar.jpg 450w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/08\/Projeto-tocar-e-encantar-225x300.jpg 225w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">A Prefeitura de Eun\u00e1polis informa que est\u00e3o abertas as inscri\u00e7\u00f5es para o projeto Tocar &amp; Encantar, que vai beneficiar 100 alunos da rede p\u00fablica municipal, com idades entre 7 e 16 anos, com aulas gratuitas de viol\u00e3o e flauta doce.<\/h3>\n<h3 style=\"text-align: justify;\">As inscri\u00e7\u00f5es podem ser feitas at\u00e9 sexta-feira (08), das 8h30 \u00e0s 14h30, na Secretaria de Esporte, Juventude, Cultura e Lazer, localizada na Pra\u00e7a de Esporte e Cultura (PEC), no bairro Itapu\u00e3. As vagas s\u00e3o limitadas.<\/h3>\n<h3 style=\"text-align: justify;\">O Tocar &amp; Encantar \u00e9 um projeto de forma\u00e7\u00e3o musical voltado para crian\u00e7as e adolescentes, com foco na inclus\u00e3o social e no desenvolvimento cultural. Durante 12 meses, os participantes ter\u00e3o aulas no contraturno escolar (turno oposto ao da escola regular) e receber\u00e3o instrumentos, uniformes e acompanhamento pedag\u00f3gico especializado, tudo de forma gratuita.<\/h3>\n<h3 style=\"text-align: justify;\">Realizado pela Forma Cultural Produ\u00e7\u00f5es Art\u00edsticas, com o apoio do Governo Federal, da Prefeitura de Eun\u00e1polis \u2014 por meio da Secretaria de Esporte, Juventude, Cultura e Lazer \u2014 e de empresas privadas, o projeto refor\u00e7a o compromisso com a valoriza\u00e7\u00e3o da juventude e o incentivo \u00e0 cultura no munic\u00edpio.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Eun\u00e1polis informa que est\u00e3o abertas as inscri\u00e7\u00f5es para o projeto Tocar &amp; Encantar, que vai beneficiar 100 alunos da rede p\u00fablica municipal, com idades entre 7 e 16 anos, com aulas gratuitas de viol\u00e3o e flauta doce. As inscri\u00e7\u00f5es podem ser feitas at\u00e9 sexta-feira (08), das 8h30 \u00e0s 14h30, na Secretaria de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":192278,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-192277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":183,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192277"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=192277"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192277\/revisions"}],"predecessor-version":[{"id":192279,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192277\/revisions\/192279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/192278"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=192277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=192277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=192277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}