
{"id":192073,"date":"2025-07-28T15:37:58","date_gmt":"2025-07-28T18:37:58","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=192073"},"modified":"2025-07-28T15:37:58","modified_gmt":"2025-07-28T18:37:58","slug":"floresta-azul-prefeito-bambu-exonera-garrafao-e-aliados","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/07\/28\/floresta-azul-prefeito-bambu-exonera-garrafao-e-aliados\/","title":{"rendered":"FLORESTA AZUL: PREFEITO BAMBU EXONERA GARRAF\u00c3O E ALIADOS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-191952\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/07\/486535591_1113937190745044_3426694891245255515_n.jpg\" alt=\"\" width=\"450\" height=\"363\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/07\/486535591_1113937190745044_3426694891245255515_n.jpg 450w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/07\/486535591_1113937190745044_3426694891245255515_n-300x242.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Nesta segunda-feira, o prefeito de Floresta Azul, Hermonio Bambu, oficializou o rompimento pol\u00edtico com o ex-prefeito Garraf\u00e3o ao exoner\u00e1-lo do cargo de secret\u00e1rio de Obras. A decis\u00e3o tamb\u00e9m atingiu pessoas ligadas ao ex-gestor.<\/h3>\n<h3 style=\"text-align: justify;\">Foram exoneradas, al\u00e9m de Garraf\u00e3o, Diana Santana, que ocupava a Secretaria de Administra\u00e7\u00e3o, e Louise Prates, da Secretaria de Sa\u00fade.<\/h3>\n<h3 style=\"text-align: justify;\">As mudan\u00e7as confirmam o fim da alian\u00e7a entre Bambu e Garraf\u00e3o, que at\u00e9 ent\u00e3o integravam o mesmo grupo pol\u00edtico. O afastamento j\u00e1 vinha sendo especulado nos bastidores e agora se concretiza com a reformula\u00e7\u00e3o no alto escal\u00e3o do governo municipal.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Nesta segunda-feira, o prefeito de Floresta Azul, Hermonio Bambu, oficializou o rompimento pol\u00edtico com o ex-prefeito Garraf\u00e3o ao exoner\u00e1-lo do cargo de secret\u00e1rio de Obras. A decis\u00e3o tamb\u00e9m atingiu pessoas ligadas ao ex-gestor. Foram exoneradas, al\u00e9m de Garraf\u00e3o, Diana Santana, que ocupava a Secretaria de Administra\u00e7\u00e3o, e Louise Prates, da Secretaria de Sa\u00fade. As mudan\u00e7as [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":191952,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-192073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":897,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192073"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=192073"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192073\/revisions"}],"predecessor-version":[{"id":192074,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/192073\/revisions\/192074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/191952"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=192073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=192073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=192073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}