
{"id":191711,"date":"2025-07-08T12:10:57","date_gmt":"2025-07-08T15:10:57","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=191711"},"modified":"2025-07-08T12:10:57","modified_gmt":"2025-07-08T15:10:57","slug":"coaraci-apresenta-selecao-para-o-intermunicipal-2025-com-apoio-total-da-gestao-municipal","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/07\/08\/coaraci-apresenta-selecao-para-o-intermunicipal-2025-com-apoio-total-da-gestao-municipal\/","title":{"rendered":"COARACI APRESENTA SELE\u00c7\u00c3O PARA O INTERMUNICIPAL 2025 COM APOIO TOTAL DA GEST\u00c3O MUNICIPAL"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-191712\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-09.13.27.jpg\" alt=\"\" width=\"450\" height=\"307\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-09.13.27.jpg 450w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-08-at-09.13.27-300x205.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Em clima de entusiasmo e expectativa, a cidade de Coaraci apresentou oficialmente, nesta semana, sua sele\u00e7\u00e3o de futebol para a disputa do Campeonato Intermunicipal 2025. A cerim\u00f4nia, promovida pela Liga Coaraciense de Futebol e presidida por Jos\u00e9 Martins dos Santos, o popular Ded\u00e9, reuniu autoridades locais, atletas, desportistas e torcedores.<\/h3>\n<h3 style=\"text-align: justify;\">A sele\u00e7\u00e3o contar\u00e1 com total apoio da Prefeitura de Coaraci, sob a gest\u00e3o do prefeito Miltinho do Ax\u00e9, que tem feito do esporte uma das prioridades da administra\u00e7\u00e3o. A recente edi\u00e7\u00e3o do Campeonato Interbairros, encerrada no \u00faltimo domingo, foi considerada uma das maiores da hist\u00f3ria do munic\u00edpio e evidenciou o compromisso da gest\u00e3o com o fortalecimento do esporte local.<\/h3>\n<h3 style=\"text-align: justify;\">O comando t\u00e9cnico da equipe estar\u00e1 nas m\u00e3os de Marcos Barbosa, ex-jogador campe\u00e3o em 2001 e vice-campe\u00e3o como treinador. Com passagens marcantes por outras sele\u00e7\u00f5es baianas, Marcos retorna ao cargo com experi\u00eancia, lideran\u00e7a e forte identifica\u00e7\u00e3o com Coaraci.<\/h3>\n<h3 style=\"text-align: justify;\">Entre os destaques do elenco, o meia Diego Porto, multicampe\u00e3o do Intermunicipal, \u00e9 a principal novidade. Sua chegada eleva o n\u00edvel t\u00e9cnico da equipe e traz mais confian\u00e7a ao grupo.<\/h3>\n<h3 style=\"text-align: justify;\">Com uma base s\u00f3lida, refor\u00e7os de peso e uma gest\u00e3o municipal atuante, a sele\u00e7\u00e3o de Coaraci inicia sua jornada com o objetivo de fazer hist\u00f3ria no Intermunicipal 2025 e devolver \u00e0 torcida a emo\u00e7\u00e3o de grandes conquistas.<\/h3>\n<h3 style=\"text-align: justify;\">A bola vai rolar \u2014 e Coaraci quer ser protagonista mais uma vez.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Em clima de entusiasmo e expectativa, a cidade de Coaraci apresentou oficialmente, nesta semana, sua sele\u00e7\u00e3o de futebol para a disputa do Campeonato Intermunicipal 2025. A cerim\u00f4nia, promovida pela Liga Coaraciense de Futebol e presidida por Jos\u00e9 Martins dos Santos, o popular Ded\u00e9, reuniu autoridades locais, atletas, desportistas e torcedores. A sele\u00e7\u00e3o contar\u00e1 com total [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":191712,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-191711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":221,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/191711"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=191711"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/191711\/revisions"}],"predecessor-version":[{"id":191713,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/191711\/revisions\/191713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/191712"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=191711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=191711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=191711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}