
{"id":191580,"date":"2025-07-01T12:13:46","date_gmt":"2025-07-01T15:13:46","guid":{"rendered":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=191580"},"modified":"2025-07-01T12:13:46","modified_gmt":"2025-07-01T15:13:46","slug":"eunapolis-bate-recorde-de-publico-e-lidera-ranking-dos-festejos-juninos-na-bahia","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2025\/07\/01\/eunapolis-bate-recorde-de-publico-e-lidera-ranking-dos-festejos-juninos-na-bahia\/","title":{"rendered":"EUN\u00c1POLIS BATE RECORDE DE P\u00daBLICO E LIDERA RANKING DOS FESTEJOS JUNINOS NA BAHIA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-191581\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/07\/pedddd.jpg\" alt=\"\" width=\"450\" height=\"300\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/07\/pedddd.jpg 450w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2025\/07\/pedddd-300x200.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Eun\u00e1polis confirmou sua posi\u00e7\u00e3o de destaque entre os maiores festejos juninos da Bahia. De acordo com informativo divulgado pela Pol\u00edcia Militar, mais de 100 mil pessoas participaram da pen\u00faltima noite do Pedr\u00e3o 2025, no s\u00e1bado (28), lotando a Arena do Est\u00e1dio Arauj\u00e3o em um dos momentos mais emocionantes da hist\u00f3ria do evento.<\/h3>\n<h3 style=\"text-align: justify;\">A cidade superou grandes polos tradicionais de festejos juninos, deixando para tr\u00e1s munic\u00edpios como Ipia\u00fa e Itabuna \u2014 que ficou em terceiro lugar no ranking, com menos de 54 mil participantes.<\/h3>\n<h3 style=\"text-align: justify;\">A noite foi marcada por uma atmosfera de emo\u00e7\u00e3o, cultura e muita anima\u00e7\u00e3o. Quem deu in\u00edcio \u00e0 festa foi a banda Cacimba Barrenta, com o aut\u00eantico forr\u00f3 nordestino que fez o p\u00fablico dan\u00e7ar do come\u00e7o ao fim.<\/h3>\n<h3 style=\"text-align: justify;\">Logo em seguida, o cantor Grelo levou irrever\u00eancia e talento ao palco, interpretando m\u00fasicas autorais que j\u00e1 s\u00e3o destaque no cen\u00e1rio nacional. O romantismo ganhou for\u00e7a com a apresenta\u00e7\u00e3o de As Donas do Bar, embalando os cora\u00e7\u00f5es apaixonados com can\u00e7\u00f5es cheias de sentimento.<\/h3>\n<h3 style=\"text-align: justify;\">A dupla Henrique &amp; Juliano entrou com um repert\u00f3rio repleto de sucessos, os sertanejos comandaram um espet\u00e1culo emocionante que uniu t\u00e9cnica e carisma, emocionando o p\u00fablico e f\u00e3s de todas as idades.<\/h3>\n<h3 style=\"text-align: justify;\">O encerramento ficou por conta da banda Cacau com Leite, que trouxe um verdadeiro arrasta-p\u00e9 com forr\u00f3 tradicional, fazendo a Arena vibrar at\u00e9 o raiar do dia.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Eun\u00e1polis confirmou sua posi\u00e7\u00e3o de destaque entre os maiores festejos juninos da Bahia. De acordo com informativo divulgado pela Pol\u00edcia Militar, mais de 100 mil pessoas participaram da pen\u00faltima noite do Pedr\u00e3o 2025, no s\u00e1bado (28), lotando a Arena do Est\u00e1dio Arauj\u00e3o em um dos momentos mais emocionantes da hist\u00f3ria do evento. A cidade superou [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":191581,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-191580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":179,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/191580"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=191580"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/191580\/revisions"}],"predecessor-version":[{"id":191582,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/191580\/revisions\/191582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media\/191581"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=191580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=191580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=191580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}