
{"id":1741,"date":"2009-11-30T21:15:36","date_gmt":"2009-12-01T00:15:36","guid":{"rendered":"http:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=1741"},"modified":"2009-11-30T21:15:36","modified_gmt":"2009-12-01T00:15:36","slug":"verba-bloqueada","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2009\/11\/30\/verba-bloqueada\/","title":{"rendered":"VERBA BLOQUEADA"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><span style=\"color: #000000;\">A prefeita de Jussari, Neone Cordeiro (PP), teve uma p\u00e9ssima surpresa nesta segunda-feira. O repasse federal de R$ 120 mil foi bloqueado, o motivo foi uma  a\u00e7\u00e3o movida pelo advogado Edmilton Carneiro.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\nEle foi o advogado que conseguiu junto a justi\u00e7a a reintegra\u00e7\u00e3o dos servidores p\u00fablicos que estavam afastados h\u00e1 mais de 5 anos. Com a decis\u00e3o da justi\u00e7a, mais de 170 funcion\u00e1rios concursados voltaram ao trabalho. Eles tinham sido exonerados pelo o ex-prefeito S\u00e9rgio Magalh\u00e3es (PR).<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\nAp\u00f3s a decis\u00e3o da justi\u00e7a ficou definido que a prefeitura pagaria o advogado Edmilton em tr\u00eas parcelas, mas o acordo n\u00e3o foi cumprido, e o advogado entrou com uma a\u00e7\u00e3o para bloquear o repasse do dia 30.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\nSegundo informa\u00e7\u00f5es, a assessoria jur\u00eddica da prefeitura vai tentar nesta ter\u00e7a-feira reverter a situa\u00e7\u00e3o.<\/span><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>A prefeita de Jussari, Neone Cordeiro (PP), teve uma p\u00e9ssima surpresa nesta segunda-feira. O repasse federal de R$ 120 mil foi bloqueado, o motivo foi uma a\u00e7\u00e3o movida pelo advogado Edmilton Carneiro. . Ele foi o advogado que conseguiu junto a justi\u00e7a a reintegra\u00e7\u00e3o dos servidores p\u00fablicos que estavam afastados h\u00e1 mais de 5 anos. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-1741","post","type-post","status-publish","format-standard","hentry","category-politica"],"views":3344,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/1741"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=1741"}],"version-history":[{"count":2,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/1741\/revisions"}],"predecessor-version":[{"id":1743,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/1741\/revisions\/1743"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=1741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=1741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=1741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}