
{"id":159646,"date":"2022-02-17T17:43:40","date_gmt":"2022-02-17T20:43:40","guid":{"rendered":"http:\/\/www.politicosdosuldabahia.com.br\/v1\/?p=159646"},"modified":"2022-02-17T17:43:40","modified_gmt":"2022-02-17T20:43:40","slug":"ibicarai-prefeita-monalisa-tavares-participa-de-sessao-que-abriu-os-trabalhos-da-camara","status":"publish","type":"post","link":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/2022\/02\/17\/ibicarai-prefeita-monalisa-tavares-participa-de-sessao-que-abriu-os-trabalhos-da-camara\/","title":{"rendered":"IBICARA\u00cd: PREFEITA MONALISA TAVARES PARTICIPA DE SESS\u00c3O QUE ABRIU OS TRABALHOS DA C\u00c2MARA"},"content":{"rendered":"<h3 style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-159647 aligncenter\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-17-at-17.40.42.jpeg\" alt=\"WhatsApp Image 2022-02-17 at 17.40.42\" width=\"455\" height=\"302\" srcset=\"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-17-at-17.40.42.jpeg 455w, https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/2022\/02\/WhatsApp-Image-2022-02-17-at-17.40.42-300x199.jpeg 300w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/h3>\n<h3 style=\"text-align: justify\">A prefeita de Ibicara\u00ed, Monalisa Tavares, participou na noite de quarta-feira, dia 16 de fevereiro, da primeira sess\u00e3o ordin\u00e1ria do ano de 2022 que abriu os trabalhos do legislativo municipal ibicaraiense.<\/h3>\n<h3 style=\"text-align: justify\">\nNa oportunidade a prefeita iniciou sua fala saudando a todos os presentes e agradecendo a Deus e aos vereadores que apoiaram e estiveram ao lado do executivo ajudando o povo na enchente de final de ano. Monalisa usou da palavra para prestar contas do dinheiro arrecadado via conta PIX para ajudar as centenas de fam\u00edlias desabrigadas pelas fortes chuvas do final de dezembro.<\/h3>\n<h3 style=\"text-align: justify\">\nMonalisa agradeceu a todos que ajudaram depositando na conta atrav\u00e9s do PIX. A gestora fez um agradecimento especial para uma m\u00e9dica chamada Alana (que n\u00e3o mora em Ibicara\u00ed), que arrecadou mais de 40 mil reais. Monalisa lembrou dos v\u00e1rios abrigos montados para atender aos desabrigados pelas chuvas e falou que a prefeitura produziu e distribuiu mais de 25 mil quentinhas, sem contar as institui\u00e7\u00f5es, clubes de servi\u00e7os e igrejas que tamb\u00e9m ajudaram de forma independente.<\/h3>\n<h3 style=\"text-align: justify\">\nSegundo a prefeita foram arrecadados R$ 114.176,13, dos quais 75 mil reais foram gastos com materiais de constru\u00e7\u00e3o e os 39 mil reais restantes foram usados com compra e doa\u00e7\u00e3o de alimentos, fog\u00f5es, colch\u00f5es e material de limpeza para as fam\u00edlias desabrigadas.<\/h3>\n<h3 style=\"text-align: justify\">\nA gestora informou que dos 39 mil reais usados para alimenta\u00e7\u00e3o, 20 mil reais foram em alimentos (quentinhas e produtos da cesta b\u00e1sica); R$ 6.641,00 em gastos com embalagens das quentinhas; R$ 8.000,00 em compra de fog\u00f5es e R$ 596,00 com material de constru\u00e7\u00e3o. Monalisa lembrou ainda que foram comprados colch\u00f5es no valor de R$ 2.500,00 e material de higiene pessoal no valor de R$ 985,00.<\/h3>\n<h3 style=\"text-align: justify\">\nPor \u00faltimo a prefeita Monalisa disse que R$ 75.087,00 foram gastos com materiais de constru\u00e7\u00e3o, sendo R$ 9.560,00 em 11 mil blocos; 720 sacos de cimento no valor de R$ 23.040,00 e 440 latas de tintas de 18 litros, dando um total de R$ 39.865,00.<\/h3>\n<h3 style=\"text-align: justify\">\nA prefeita Monalisa e equipe fizeram a entrega desse material nessa quinta-feira, dia 17.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A prefeita de Ibicara\u00ed, Monalisa Tavares, participou na noite de quarta-feira, dia 16 de fevereiro, da primeira sess\u00e3o ordin\u00e1ria do ano de 2022 que abriu os trabalhos do legislativo municipal ibicaraiense. Na oportunidade a prefeita iniciou sua fala saudando a todos os presentes e agradecendo a Deus e aos vereadores que apoiaram e estiveram ao [&hellip;]<\/p>\n","protected":false},"author":992,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"class_list":["post-159646","post","type-post","status-publish","format-standard","hentry","category-cidades"],"views":479,"_links":{"self":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/159646"}],"collection":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/users\/992"}],"replies":[{"embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/comments?post=159646"}],"version-history":[{"count":1,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/159646\/revisions"}],"predecessor-version":[{"id":159648,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/posts\/159646\/revisions\/159648"}],"wp:attachment":[{"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/media?parent=159646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/categories?post=159646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-json\/wp\/v2\/tags?post=159646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}